{"id":4110,"date":"2024-08-13T17:06:18","date_gmt":"2024-08-13T17:06:18","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=4110"},"modified":"2024-08-13T17:06:21","modified_gmt":"2024-08-13T17:06:21","slug":"ave-silvestre-e-vista-no-centro-de-apucarana","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2024\/08\/13\/ave-silvestre-e-vista-no-centro-de-apucarana\/","title":{"rendered":"Ave silvestre \u00e9 vista no centro de Apucarana"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"530\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/08\/Seriema_Cariama_cristata.jpg\" alt=\"\" class=\"wp-image-4111\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/08\/Seriema_Cariama_cristata.jpg 800w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/08\/Seriema_Cariama_cristata-300x199.jpg 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/08\/Seriema_Cariama_cristata-768x509.jpg 768w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/08\/Seriema_Cariama_cristata-400x265.jpg 400w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/08\/Seriema_Cariama_cristata-700x464.jpg 700w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/08\/Seriema_Cariama_cristata-600x398.jpg 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<p>Na data de ontem, 12, moradores de&nbsp;Apucarana ficaram surpresos ao se depararem com uma&nbsp;ave silvestre na regi\u00e3o central.<\/p>\n\n\n\n<p>Equipes do meio ambiente foram mobilizadas para realizar a captura da seriema, os trabalhos de captura do animal vem sendo realizados desde o avistamento da ave, que cruzou &nbsp;alguns bairros da cidade at\u00e9 chegar a \u00e1rea central.<\/p>\n\n\n\n<p>A seriema pode chegar at\u00e9 90 cent\u00edmetros de comprimento pesando &nbsp;em m\u00e9dia 1,4 kg. Tem no canto a sua principal caracter\u00edstica, podendo ser ouvida a mais de um quil\u00f4metro de dist\u00e2ncia, \u00e9 uma ave em extin\u00e7\u00e3o. Apesar de ser uma ave, a seriema n\u00e3o gosta de voar, prefere correr. Sua velocidade pode chegar facilmente a 50 km\/h, s\u00f3 ent\u00e3o al\u00e7ando voo. Mesmo assim, apenas em situa\u00e7\u00f5es extremas, como quando ca\u00e7ada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na data de ontem, 12, moradores de&nbsp;Apucarana ficaram surpresos ao se depararem com uma&nbsp;ave silvestre na regi\u00e3o central. Equipes do meio ambiente foram mobilizadas para realizar a captura da seriema, os trabalhos de captura do animal vem sendo realizados desde o avistamento da ave, que cruzou &nbsp;alguns bairros da cidade at\u00e9 chegar a \u00e1rea central. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4110","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/4110","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=4110"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/4110\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=4110"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=4110"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=4110"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}