{"id":4102,"date":"2024-06-10T12:43:03","date_gmt":"2024-06-10T12:43:03","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=4102"},"modified":"2024-06-10T12:43:28","modified_gmt":"2024-06-10T12:43:28","slug":"em-2-anos-restaurante-popular-de-apucarana-serviu-150-mil-refeicoes","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2024\/06\/10\/em-2-anos-restaurante-popular-de-apucarana-serviu-150-mil-refeicoes\/","title":{"rendered":"Em 2 anos, Restaurante Popular de Apucarana serviu 150 mil refei\u00e7\u00f5es"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"960\" height=\"509\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/06\/refeicao.jpg\" alt=\"\" class=\"wp-image-4103\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/06\/refeicao.jpg 960w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/06\/refeicao-300x159.jpg 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/06\/refeicao-768x407.jpg 768w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/06\/refeicao-400x212.jpg 400w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/06\/refeicao-700x371.jpg 700w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/06\/refeicao-600x318.jpg 600w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/figure>\n\n\n\n<p>O Restaurante Popular de Apucarana, implantado em 2022 pela Prefeitura, por meio da Secretaria de Assist\u00eancia Social, completou dois anos de atividades nesta semana. O programa, que integra o conjunto de a\u00e7\u00f5es voltadas ao atendimento de necessidades alimentares e nutricionais da popula\u00e7\u00e3o socialmente vulner\u00e1vel, acaba de atingir o patamar de 150 mil refei\u00e7\u00f5es servidas, ao custo unit\u00e1rio de R$2,00.<\/p>\n\n\n\n<p>Idealizado pelo prefeito J\u00fanior da Femac, o programa \u00e9 coordenado pela superintendente Eliana Rocha, da Secretaria Municipal da Assist\u00eancia Social, com apoio da C\u00e2mara Intersetorial de Seguran\u00e7a Alimentar e Nutricional de Apucarana. Pelo prato-feito, que conta com card\u00e1pio di\u00e1rio variado definido e supervisionado por nutricionistas, o cidad\u00e3o paga apenas R$2,00 (dois reais), sendo o custo adicional custeado pelo munic\u00edpio. \u201cCriamos o restaurante Popular para garantir uma refei\u00e7\u00e3o di\u00e1ria de qualidade, a um custo bem acess\u00edvel\u201d, enfatiza o prefeito Junior da Femac. Ele acrescenta que a iniciativa soma-se a outras pol\u00edticas de gest\u00e3o, com foco num \u00fanico objetivo: \u201cQue ningu\u00e9m passe fome em Apucarana\u201d, assinala o prefeito J\u00fanior da Femac.<\/p>\n\n\n\n<p>Diariamente s\u00e3o servidas 300 refei\u00e7\u00f5es. Al\u00e9m de arroz e feij\u00e3o, o card\u00e1pio contempla carnes, legumes, verduras, massas e frutas de sobremesa, com pelo menos 30% dos alimentos sendo adquiridos junto \u00e0 agricultura familiar de Apucarana. No in\u00edcio, em junho de 2022, eram servidas 200 refei\u00e7\u00f5es, mas a curto prazo foi preciso ampliar a oferta, diante da demanda crescente.<\/p>\n\n\n\n<p>Na equipe desde o in\u00edcio das atividades, a coordenadora do Restaurante Popular, Eliana Rocha, assinala que a iniciativa vem atendendo aos seus objetivos. \u201cEstamos atendendo as necessidades alimentar e nutricional de gestantes, aposentados, estudantes, pessoas de baixa-renda em busca de um emprego e em tratamento de sa\u00fade, al\u00e9m de moradores em situa\u00e7\u00e3o de rua\u201d, pontua a coordenadora, que comemora o sucesso do programa.<\/p>\n\n\n\n<p>\u201c\u00c9 muito gratificante acompanhar todo este processo idealizado pelo prefeito J\u00fanior da Femac, assegurando uma alimenta\u00e7\u00e3o saud\u00e1vel e a um pre\u00e7o baix\u00edssimo\u201d, diz Eliana Rocha, emendando que \u201cno dia a dia observamos as dificuldades das pessoas que atendemos, principalmente os idosos\u201d.<\/p>\n\n\n\n<p>USU\u00c1RIOS APROVAM \u2013&nbsp;O secret\u00e1rio de Assist\u00eancia Social, Juliano Dalla Costa relata que, com o funcionamento em espa\u00e7o na \u00e1rea central da cidade, o restaurante facilita o acesso de idosos, trabalhadores em geral, e at\u00e9 pessoas em tratamento de sa\u00fade do Hospital da Provid\u00eancia, do Cisvir e da Adefiap.<\/p>\n\n\n\n<p>O prato refor\u00e7ado de Raul Carlos Maximiliano, 58 anos, morador da Vila Nova tem uma justificativa. \u201cEssa \u00e9 praticamente a minha \u00fanica refei\u00e7\u00e3o do dia. Moro sozinho e minha renda \u00e9 gerada como catador de latinhas. O que economizo na alimenta\u00e7\u00e3o ajuda muito para pagar as outras despesas. Aqui a comida \u00e9 \u00f3tima. Tenho alimento e de gra\u00e7a. Foi por obra de Deus que a prefeitura abriu esse restaurante. Isso n\u00e3o pode acabar\u201d, relata Maximiliano, que almo\u00e7a todos os dias no Restaurante Popular.<\/p>\n\n\n\n<p>Paulo Matias e a esposa Aparecida tamb\u00e9m almo\u00e7am todos os dias no Restaurante Popular. \u201cEste \u00e9, sem d\u00favida, um dos melhores programas que a prefeitura fez para atender quem tem menor condi\u00e7\u00e3o financeira, e tamb\u00e9m ajuda muito os idosos. O restaurante \u00e9 o verdadeiro \u00b4fome zero`. Aqui as pessoas se alimentam bem e s\u00e3o sempre bem atendidas. A comida \u00e9 deliciosa e recebemos alimento saud\u00e1vel\u201d, avalia Paulo Matias, de 74 anos e morador do N\u00facleo Habitacional Osmar Guaraci Freire.<\/p>\n\n\n\n<p><strong>Servi\u00e7o:<\/strong>&nbsp;O atendimento do Restaurante Popular \u00e9 de segunda a sexta-feira, das 11 horas \u00e0s 14 horas, com o caixa aberto at\u00e9 o limite de venda das 300 refei\u00e7\u00f5es\/dia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Restaurante Popular de Apucarana, implantado em 2022 pela Prefeitura, por meio da Secretaria de Assist\u00eancia Social, completou dois anos de atividades nesta semana. O programa, que integra o conjunto de a\u00e7\u00f5es voltadas ao atendimento de necessidades alimentares e nutricionais da popula\u00e7\u00e3o socialmente vulner\u00e1vel, acaba de atingir o patamar de 150 mil refei\u00e7\u00f5es servidas, ao [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4102","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/4102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=4102"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/4102\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=4102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=4102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=4102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}