{"id":4064,"date":"2024-05-29T12:44:52","date_gmt":"2024-05-29T12:44:52","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=4064"},"modified":"2024-05-29T12:44:53","modified_gmt":"2024-05-29T12:44:53","slug":"guarda-civil-municipal-de-apucarana-tem-aprovacao-para-atuar-armada","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2024\/05\/29\/guarda-civil-municipal-de-apucarana-tem-aprovacao-para-atuar-armada\/","title":{"rendered":"Guarda Civil Municipal de Apucarana tem aprova\u00e7\u00e3o para atuar armada"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/05\/civil-1024x768.jpg\" alt=\"\" class=\"wp-image-4065\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/05\/civil-1024x768.jpg 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/05\/civil-300x225.jpg 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/05\/civil-768x576.jpg 768w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/05\/civil-1536x1152.jpg 1536w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/05\/civil-400x300.jpg 400w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/05\/civil-700x525.jpg 700w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/05\/civil-600x450.jpg 600w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/05\/civil.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Encontro com o prefeito de\u00a0Apucarana, Junior da Femac (MDB), por meio dos segmentos organizados, sobre a Guarda Civil Municipal (GCM) passar a atuar armada, foi aprovado por unanimidade pelas lideran\u00e7as presentes que a corpora\u00e7\u00e3o atue com armamento letal.<\/p>\n\n\n\n<p>Atualmente, a guarda atua apenas com as pistolas Teaser, para imobiliza\u00e7\u00e3o em situa\u00e7\u00f5es de emerg\u00eancia. A Lei que autoriza o porte de arma para Guardas Civis Municipais est\u00e1 em vigor desde o ano de 2013.<\/p>\n\n\n\n<p>Ainda, no final do encontro, o prefeito anunciou que j\u00e1 vai encaminhar para a C\u00e2mara de Vereadores projetos de lei que viabilizam a institui\u00e7\u00e3o da guarda armada e tamb\u00e9m criam a Ouvidoria e a Corregedoria da Guarda Civil Municipal, que s\u00e3o dispositivos legais que fiscalizam a atua\u00e7\u00e3o dos agentes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Encontro com o prefeito de\u00a0Apucarana, Junior da Femac (MDB), por meio dos segmentos organizados, sobre a Guarda Civil Municipal (GCM) passar a atuar armada, foi aprovado por unanimidade pelas lideran\u00e7as presentes que a corpora\u00e7\u00e3o atue com armamento letal. Atualmente, a guarda atua apenas com as pistolas Teaser, para imobiliza\u00e7\u00e3o em situa\u00e7\u00f5es de emerg\u00eancia. A Lei [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-4064","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/4064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=4064"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/4064\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=4064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=4064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=4064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}