{"id":392,"date":"2023-09-08T18:25:13","date_gmt":"2023-09-08T18:25:13","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=392"},"modified":"2023-09-08T18:25:13","modified_gmt":"2023-09-08T18:25:13","slug":"morador-de-rua-e-morto-a-pedradas-corpo-foi-encontrado-por-criancas","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2023\/09\/08\/morador-de-rua-e-morto-a-pedradas-corpo-foi-encontrado-por-criancas\/","title":{"rendered":"Morador de rua \u00e9 morto a pedradas; corpo foi encontrado por crian\u00e7as"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>As crian\u00e7as brincavam quando se depararam com o corpo; a v\u00edtima foi morta depois de ser atingida com uma pedra de mais de sete quilos<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/Pedra-utilizada-no-crime-00790945-0-202309081517-ScaleDownProportional.webp\" alt=\"\" class=\"wp-image-393\" style=\"width:664px;height:317px\" width=\"664\" height=\"317\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/Pedra-utilizada-no-crime-00790945-0-202309081517-ScaleDownProportional.webp 891w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/Pedra-utilizada-no-crime-00790945-0-202309081517-ScaleDownProportional-600x287.webp 600w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/Pedra-utilizada-no-crime-00790945-0-202309081517-ScaleDownProportional-300x143.webp 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/09\/Pedra-utilizada-no-crime-00790945-0-202309081517-ScaleDownProportional-768x367.webp 768w\" sizes=\"(max-width: 664px) 100vw, 664px\" \/><\/figure>\n\n\n\n<p>Crian\u00e7as que brincavam pr\u00f3ximo a um sal\u00e3o comunit\u00e1rio ficaram assustadas ao se depararem com um corpo no fim da tarde dessa quinta-feira, 7 de setembro, no Bairro Santa Felicidade, em\u00a0<a href=\"https:\/\/tnonline.uol.com.br\/tags\/cascavel?d=1\">Cascavel<\/a>, oeste do Paran\u00e1. De acordo com as informa\u00e7\u00f5es da Pol\u00edcia Civil (PC), a v\u00edtima, identificada como Elizeu Caliari de 50 anos, foi morta a pedradas por um jovem de 25 anos, que confessou o crime.<\/p>\n\n\n\n<p>\u00c0 imprensa, o delegado que est\u00e1 \u00e0 frente do caso, Fabiano Mozza, disse que Elizeu vivia em situa\u00e7\u00e3o de rua e foi agredido com peda\u00e7os de madeira antes de ser morto. O respons\u00e1vel pelo crime deu detalhes \u00e0s autoridades de como assassinou a v\u00edtima.<\/p>\n\n\n\n<p><em>&#8220;Ele confessou o crime, relatou que o autor teria desferido um tapa em seu rosto e lhe xingado. Ele sabia que o autor era morador de rua e dormia ali. Ele esperou o autor dormir, voltou na madrugada de quarta para quinta e matou o autor com essa pedra de 7 kg&#8221;<\/em>, afirmou o delegado.<\/p>\n\n\n\n<p><em>&#8220;Falou com requinte de crueldade, com detalhe, que colocou at\u00e9 uma manta na cabe\u00e7a para n\u00e3o expirar sangue nele porque o autor j\u00e1 estava desacordado e efetuou tr\u00eas golpes (com a pedra)&#8221;<\/em>, disse o delegado.<\/p>\n\n\n\n<p>A Pol\u00edcia Civil afirmou que o suspeito pelo crime passou por audi\u00eancia de cust\u00f3dia nesta sexta-feira (8) e permanece preso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As crian\u00e7as brincavam quando se depararam com o corpo; a v\u00edtima foi morta depois de ser atingida com uma pedra de mais de sete quilos Crian\u00e7as que brincavam pr\u00f3ximo a um sal\u00e3o comunit\u00e1rio ficaram assustadas ao se depararem com um corpo no fim da tarde dessa quinta-feira, 7 de setembro, no Bairro Santa Felicidade, em\u00a0Cascavel, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-392","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/392","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=392"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/392\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=392"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=392"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=392"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}