{"id":3877,"date":"2024-05-22T12:40:08","date_gmt":"2024-05-22T12:40:08","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=3877"},"modified":"2024-05-22T12:40:12","modified_gmt":"2024-05-22T12:40:12","slug":"homem-e-preso-apos-realizar-pagamentos-com-notas-falsas-em-apucarana","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2024\/05\/22\/homem-e-preso-apos-realizar-pagamentos-com-notas-falsas-em-apucarana\/","title":{"rendered":"Homem \u00e9 preso ap\u00f3s realizar pagamentos com notas falsas em Apucarana"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"984\" height=\"738\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/05\/falsa.jpg\" alt=\"\" class=\"wp-image-3878\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/05\/falsa.jpg 984w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/05\/falsa-300x225.jpg 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/05\/falsa-768x576.jpg 768w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/05\/falsa-400x300.jpg 400w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/05\/falsa-700x525.jpg 700w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/05\/falsa-600x450.jpg 600w\" sizes=\"(max-width: 984px) 100vw, 984px\" \/><\/figure>\n\n\n\n<p>Homem \u00e9 preso depois de abastecer em um posto de combust\u00edveis localizado no centro de\u00a0Apucarana\u00a0e efetuar o pagamento com notas falsas. O frentista entregou as notas para o gerente, que percebeu se tratar de notas falsas, chamou a pol\u00edcia e seguiu o suspeito, que o amea\u00e7ou com uma arma de fogo.<\/p>\n\n\n\n<p>O homem foi localizado e reconhecido pelo gerente do posto de combust\u00edveis. Diante da amea\u00e7a com arma de fogo descrita, os policiais realizaram buscas e encontraram uma espingarda de chumbinho modificada para calibre 22. A arma foi apreendida pelas autoridades e o condutor recebeu voz de pris\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Homem \u00e9 preso depois de abastecer em um posto de combust\u00edveis localizado no centro de\u00a0Apucarana\u00a0e efetuar o pagamento com notas falsas. O frentista entregou as notas para o gerente, que percebeu se tratar de notas falsas, chamou a pol\u00edcia e seguiu o suspeito, que o amea\u00e7ou com uma arma de fogo. O homem foi localizado [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-3877","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/3877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=3877"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/3877\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=3877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=3877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=3877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}