{"id":2692,"date":"2024-05-03T13:02:15","date_gmt":"2024-05-03T13:02:15","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=2692"},"modified":"2024-05-03T13:02:18","modified_gmt":"2024-05-03T13:02:18","slug":"caminhada-eco-religiosa-da-paroquia-nossa-senhora-de-fatima-sera-neste-domingo-inscricoes-abertas","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2024\/05\/03\/caminhada-eco-religiosa-da-paroquia-nossa-senhora-de-fatima-sera-neste-domingo-inscricoes-abertas\/","title":{"rendered":"Caminhada Eco Religiosa da Par\u00f3quia Nossa Senhora de F\u00e1tima ser\u00e1 neste domingo: inscri\u00e7\u00f5es abertas"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"780\" height=\"533\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/05\/caminhada.jpg\" alt=\"\" class=\"wp-image-2693\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/05\/caminhada.jpg 780w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/05\/caminhada-600x410.jpg 600w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/05\/caminhada-300x205.jpg 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/05\/caminhada-768x525.jpg 768w\" sizes=\"(max-width: 780px) 100vw, 780px\" \/><\/figure>\n\n\n\n<p>Ser\u00e1 realizada no pr\u00f3ximo domingo (5), a 9\u00aa Caminhada Eco Religiosa da Par\u00f3quia Nossa Senhora de F\u00e1tima, no N\u00facleo Jo\u00e3o Paulo. As inscri\u00e7\u00f5es podem ser feitas diretamente da secretaria da igreja ou pelo WhatsApp (43) 99860-0777.<\/p>\n\n\n\n<p>O percurso de 6,5 km \u00e9 entre a Par\u00f3quia Nossa Senhora de F\u00e1tima, onde ser\u00e1 servido um caf\u00e9 da manh\u00e3 gratuito, e o Parque da Reden\u00e7\u00e3o. Ao longo do trajeto os participantes encontraram altares montados pelos propriet\u00e1rios rurais.<\/p>\n\n\n\n<p>A chegada ao parque da Reden\u00e7\u00e3o est\u00e1 prevista por volta das 10 horas. No local ser\u00e1 celebrada uma missa. Os participantes ter\u00e3o \u00f4nibus gratuito para retornar at\u00e9 a Par\u00f3quia Nossa Senhora de F\u00e1tima. Ser\u00e1 servido almo\u00e7o (frango com polenta) opcional no sal\u00e3o paroquial no custo de R$ 35. O cart\u00e3o deve ser adquirido com anteced\u00eancia.&nbsp;A caminhada conta com o apoio da prefeitura de Apucarana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ser\u00e1 realizada no pr\u00f3ximo domingo (5), a 9\u00aa Caminhada Eco Religiosa da Par\u00f3quia Nossa Senhora de F\u00e1tima, no N\u00facleo Jo\u00e3o Paulo. As inscri\u00e7\u00f5es podem ser feitas diretamente da secretaria da igreja ou pelo WhatsApp (43) 99860-0777. O percurso de 6,5 km \u00e9 entre a Par\u00f3quia Nossa Senhora de F\u00e1tima, onde ser\u00e1 servido um caf\u00e9 da [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2692","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/2692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=2692"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/2692\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=2692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=2692"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=2692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}