{"id":2667,"date":"2024-04-30T12:10:37","date_gmt":"2024-04-30T12:10:37","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=2667"},"modified":"2024-04-30T12:10:39","modified_gmt":"2024-04-30T12:10:39","slug":"casamento-coletivo-tem-107-casais-inscritos","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2024\/04\/30\/casamento-coletivo-tem-107-casais-inscritos\/","title":{"rendered":"Casamento coletivo tem 107 casais inscritos"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/04\/casamento-1.jpg\" alt=\"\" class=\"wp-image-2668\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/04\/casamento-1.jpg 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/04\/casamento-1-600x337.jpg 600w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/04\/casamento-1-300x168.jpg 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/04\/casamento-1-768x431.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Com 107 casais inscritos, termina nesta ter\u00e7a-feira (30) o prazo de cadastramento para o casamento civil coletivo gratuito por meio do Programa Justi\u00e7a no Bairro\/Sesc Cidad\u00e3o. A cerim\u00f4nia ser\u00e1 realizada no dia 11 de maio, \u00e0s 16 horas, no Centro Cultural F\u00eanix.<\/p>\n\n\n\n<p>\u201cO interesse est\u00e1 sendo muito grande, mas ainda h\u00e1 tempo para novos casais se inscreverem junto ao Centro de Refer\u00eancia de Assist\u00eancia Social (CRAS) mais pr\u00f3ximo de sua resid\u00eancia\u201d, convida assessor Jur\u00eddico Especial da Procuradoria Geral do Munic\u00edpio, Dr. Danylo Acioli.<\/p>\n\n\n\n<p>O casamento civil coletivo \u00e9 uma realiza\u00e7\u00e3o do Tribunal de Justi\u00e7a do Estado do Paran\u00e1 (TJ-PR), em parceria com o Sistema Fecom\u00e9rcio Paran\u00e1 e Prefeitura de Apucarana, dentro do Programa \u201cJusti\u00e7a no Bairro\u201d, uma iniciativa de responsabilidade social idealizada e coordenada pela 1\u00aa vice-presidente TJ-PR, desembargadora Joeci Machado Camargo. Participam ainda do evento a Companhia de Saneamento do Paran\u00e1 (Sanepar), Pol\u00edcia Militar do Paran\u00e1, Instituto das Cidades Inteligentes (ICI) e Ligga Telecom.<\/p>\n\n\n\n<p><strong><u>Documentos necess\u00e1rios para inscri\u00e7\u00e3o no casamento coletivo<\/u><\/strong><strong>&nbsp;*<\/strong><\/p>\n\n\n\n<p>\u2013 Documento de Identidade: RG e CPF;<br>\u2013 Certid\u00e3o de Nascimento\/casamento\/div\u00f3rcio (atualizadas);<br>\u2013 Comprovante de resid\u00eancia dos noivos \u2013 original e atualizado (conta de luz ou \u00e1gua);<br>\u2013 Comprovante de renda de at\u00e9 um sal\u00e1rio m\u00ednimo e meio por pessoa ou tr\u00eas sal\u00e1rios m\u00ednimos por casal.<br><em>* As inscri\u00e7\u00f5es precisam ser realizadas antecipadamente para habilita\u00e7\u00e3o dos casais \u2013 at\u00e9 30 de abril.<\/em><\/p>\n\n\n\n<p><strong><u>Para mais informa\u00e7\u00f5es, consulte o CRAS mais pr\u00f3ximo<\/u><\/strong><strong>&nbsp;*<\/strong><\/p>\n\n\n\n<p><strong>CRAS I&nbsp;<\/strong>\u2013 Avenida Central do Paran\u00e1, 1420 \u2013 Jardim Am\u00e9rica.<br>Telefones: (43) 3308-1451.<\/p>\n\n\n\n<p><strong>CRAS II&nbsp;<\/strong>\u2013 Rua Ilson Ferreira Guerra, 15 \u2013 Residencial Sumatra II.<br>Telefones: (43) 3308-1452.<\/p>\n\n\n\n<p><strong>CRAS III<\/strong>&nbsp;\u2013 Rua Jos\u00e9 Garcia Perez, 111 \u2013 Vila Reis.<br>Telefones: (43) 3308-1453.<\/p>\n\n\n\n<p><strong>CRAS IV&nbsp;<\/strong>\u2013 Travessa Padre Tito Cerassoli, 63 \u2013 Jardim Am\u00e9rica.<br>Telefones: (43) 3308-1454.<\/p>\n\n\n\n<p><strong>CRAS de Apoio ao CRAS I<\/strong>&nbsp;\u2013 Rua Cec\u00edlio Luz, 145 \u2013 Loteamento Sanches dos Santos.<br>Telefones: (43) 3308-1449<br><strong><br><\/strong><strong>CRAS de Apoio ao CRAS III&nbsp;<\/strong>\u2013 Rua Santa Rita, 202 \u2013 Vila Nossa Senhora da Aparecida.<br>Telefones: (43) 3308-1420.<\/p>\n\n\n\n<p><em>* O atendimento em todas as unidades acontece de segunda a sexta-feira, das 8 \u00e0s 17 horas.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com 107 casais inscritos, termina nesta ter\u00e7a-feira (30) o prazo de cadastramento para o casamento civil coletivo gratuito por meio do Programa Justi\u00e7a no Bairro\/Sesc Cidad\u00e3o. A cerim\u00f4nia ser\u00e1 realizada no dia 11 de maio, \u00e0s 16 horas, no Centro Cultural F\u00eanix. \u201cO interesse est\u00e1 sendo muito grande, mas ainda h\u00e1 tempo para novos casais [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2667","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/2667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=2667"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/2667\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=2667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=2667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=2667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}