{"id":2377,"date":"2024-04-08T13:49:16","date_gmt":"2024-04-08T13:49:16","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=2377"},"modified":"2024-04-08T13:49:18","modified_gmt":"2024-04-08T13:49:18","slug":"prefeitura-de-apucarana-recebe-recursos-federais-que-somam-quase-r1-milhao","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2024\/04\/08\/prefeitura-de-apucarana-recebe-recursos-federais-que-somam-quase-r1-milhao\/","title":{"rendered":"Prefeitura de Apucarana recebe recursos federais que somam quase R$1 milh\u00e3o."},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"665\" height=\"438\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/04\/preferitura.jpg\" alt=\"\" class=\"wp-image-2378\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/04\/preferitura.jpg 665w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/04\/preferitura-600x395.jpg 600w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/04\/preferitura-300x198.jpg 300w\" sizes=\"(max-width: 665px) 100vw, 665px\" \/><\/figure>\n<\/div>\n\n\n<p>A Prefeitura de Apucarana, recebeu nesta sexta-feira (5), recursos federais que somam quase R$1 milh\u00e3o. S\u00e3o duas emendas liberadas pela deputada federal, Gleisi Hoffmann, no valor de R$700 mil; e mais uma do deputado federal Elton Welter, de R$250 mil.<\/p>\n\n\n\n<p>O prefeito Junior da Femac fez quest\u00e3o de agradecer o deputado Arilson Chiorato e sua esposa Jane Reis, pela conquista destes recursos. \u201cOs recursos do Governo Federal ser\u00e3o importantes para custear cirurgias eletivas para idosos (catarata), mulheres (ginecol\u00f3gicas) e para crian\u00e7as (ortopedia)\u201d, disse Junior da Femac.<\/p>\n\n\n\n<p>O secret\u00e1rio de Sa\u00fade, Em\u00eddio Bachiega, manifestou sua alegria por receber este refor\u00e7o no or\u00e7amento da sa\u00fade p\u00fablica de Apucarana. \u201cAgrade\u00e7o ao Arilson a Jane e o Dr. Odarlone, que atuaram para obter as emendas com a deputada Gleisi Hoffmann e o deputado Elton Welter\u201d, disse o secret\u00e1rio, anunciando que \u201cas cirurgias come\u00e7am a ser autorizadas em breve, via Cons\u00f3rcio Intermunicipal de Sa\u00fade do Vale do Iva\u00ed e Regi\u00e3o (Cisvir)\u201d.<\/p>\n\n\n\n<p>As emendas parlamentares ao Or\u00e7amento Geral da Uni\u00e3o de 2024, via Fundo Nacional de Sa\u00fade, no valor de R$950 mil j\u00e1 est\u00e3o depositadas em conta espec\u00edfica da Autarquia Municipal de Sa\u00fade de Apucarana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Apucarana, recebeu nesta sexta-feira (5), recursos federais que somam quase R$1 milh\u00e3o. S\u00e3o duas emendas liberadas pela deputada federal, Gleisi Hoffmann, no valor de R$700 mil; e mais uma do deputado federal Elton Welter, de R$250 mil. O prefeito Junior da Femac fez quest\u00e3o de agradecer o deputado Arilson Chiorato e sua [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2377","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/2377","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=2377"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/2377\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=2377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=2377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=2377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}