{"id":2367,"date":"2024-03-07T12:43:53","date_gmt":"2024-03-07T12:43:53","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=2367"},"modified":"2024-03-07T12:43:57","modified_gmt":"2024-03-07T12:43:57","slug":"conecta-mostra-planejamento-para-2024-com-aporte-de-r500-mil-da-prefeitura","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2024\/03\/07\/conecta-mostra-planejamento-para-2024-com-aporte-de-r500-mil-da-prefeitura\/","title":{"rendered":"Conecta mostra planejamento para 2024, com aporte de R$500 mil da prefeitura"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/03\/image-6.png\" alt=\"\" class=\"wp-image-2368\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/03\/image-6.png 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/03\/image-6-600x400.png 600w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/03\/image-6-300x200.png 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/03\/image-6-768x512.png 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Em evento que reuniu representantes do setor p\u00fablico, privado e academias de Apucarana, aconteceu na manh\u00e3 desta ter\u00e7a-feira (06), no audit\u00f3rio da ACIA, a apresenta\u00e7\u00e3o do Planejamento do Conecta para 2024.<\/p>\n\n\n\n<p>O presidente da ACIA e do Conecta, Wanderlei Faganello informou que as a\u00e7\u00f5es de inova\u00e7\u00e3o j\u00e1 come\u00e7am a dar frutos no munic\u00edpio. \u201cEm 2023 atingimos quase 5.000 pessoas em 111 eventos\u201d, explica Faganello. Em sua fala de abertura, Faganello ainda frisou que Apucarana teve um amadurecimento de 17% na nota como Ecossistema de Inova\u00e7\u00e3o. \u201cCom isso recebemos do Governo do Estado, atrav\u00e9s da Secretaria de Estado da Inova\u00e7\u00e3o, Moderniza\u00e7\u00e3o e Transforma\u00e7\u00e3o digital \u2013 SEPARTEC \u2013 o CERTIFICADO HUB CONECTA APUCARANA, o que fez com que nossa cidade possa vir a receber um parque tecnol\u00f3gico em benef\u00edcio de Apucarana e toda a regi\u00e3o\u201d, ressalta Faganello.<\/p>\n\n\n\n<p>O prefeito de Apucarana, Junior da Femac, colocou a prefeitura \u00e0 disposi\u00e7\u00e3o do Conecta. \u201cPretendemos oferecer um espa\u00e7o f\u00edsico para que a governan\u00e7a se re\u00fana e possa realizar mais a\u00e7\u00f5es. Porque quero muito que possamos juntar inova\u00e7\u00e3o com educa\u00e7\u00e3o. E o Conecta pode nos ajudar muito neste sentido\u201d, diz o prefeito.<\/p>\n\n\n\n<p>No ano passado foi aprovada a Lei do Sandbox e a Lei do Empreendedorismo. \u201cA primeira facilita abertura de empresas e testes de modelagens de neg\u00f3cios para empresas inovadoras. A segunda disp\u00f5e de facilidades fiscais onde j\u00e1 temos R$ 250 mil do Fundo Municipal de Inova\u00e7\u00e3o. Contudo, podemos conceder um aporte de mais R$ 250 mil para neg\u00f3cios inovadores\u201d, promete o prefeito Junior da Femac.<\/p>\n\n\n\n<p>O consultor do Sebrae, Tiago Cunha, apresentou o Mapeamento do Ecossistema de Inova\u00e7\u00e3o, que \u00e9 um estudo que est\u00e1 sendo feito desde 2020 em Apucarana. Este trabalho faz parte das a\u00e7\u00f5es desenvolvidas pelo Conecta e Sebrae, que realizou o levantamento de dados e apontou quatro \u00e1reas com oportunidades para se empreender e para o desenvolvimento cient\u00edfico\/tecnol\u00f3gico no munic\u00edpio e na regi\u00e3o.<\/p>\n\n\n\n<p>\u201cTemos muito forte hoje o setor de mec\u00e2nica e automa\u00e7\u00e3o, agroneg\u00f3cio, computa\u00e7\u00e3o e produ\u00e7\u00e3o de qu\u00edmicos e materiais como nichos a serem investidos. A atualiza\u00e7\u00e3o do mapeamento \u00e9 importante, porque norteia o caminho das a\u00e7\u00f5es que vamos definir junto aos setores p\u00fablicos, universidades e escolas com o setor privado\u201d, explica Cunha.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em evento que reuniu representantes do setor p\u00fablico, privado e academias de Apucarana, aconteceu na manh\u00e3 desta ter\u00e7a-feira (06), no audit\u00f3rio da ACIA, a apresenta\u00e7\u00e3o do Planejamento do Conecta para 2024. O presidente da ACIA e do Conecta, Wanderlei Faganello informou que as a\u00e7\u00f5es de inova\u00e7\u00e3o j\u00e1 come\u00e7am a dar frutos no munic\u00edpio. \u201cEm 2023 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2367","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/2367","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=2367"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/2367\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=2367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=2367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=2367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}