{"id":2339,"date":"2024-02-29T18:37:41","date_gmt":"2024-02-29T18:37:41","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=2339"},"modified":"2024-02-29T18:37:44","modified_gmt":"2024-02-29T18:37:44","slug":"apucarana-instala-luminarias-led-na-rua-denhei-kanashiro","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2024\/02\/29\/apucarana-instala-luminarias-led-na-rua-denhei-kanashiro\/","title":{"rendered":"Apucarana instala lumin\u00e1rias LED na rua Denhei Kanashiro"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/02\/image-20.png\" alt=\"\" class=\"wp-image-2340\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/02\/image-20.png 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/02\/image-20-600x400.png 600w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/02\/image-20-300x200.png 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/02\/image-20-768x512.png 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>A ilumina\u00e7\u00e3o p\u00fablica da Rua Denhei Kanashiro, uma das principais vias de liga\u00e7\u00e3o entre bairros na regi\u00e3o leste de Apucarana, ser\u00e1 servida por tecnologia LED. A substitui\u00e7\u00e3o das antigas l\u00e2mpadas vapor met\u00e1lico 250 watts, por novas na pot\u00eancia 150 watts, teve in\u00edcio nesta quarta-feira (28\/02) e \u00e9 uma a\u00e7\u00e3o que integra o plano municipal de moderniza\u00e7\u00e3o do sistema de ilumina\u00e7\u00e3o p\u00fablica.<\/p>\n\n\n\n<p>Ao todo, o trabalho contempla 64 pontos. Os novos servi\u00e7os, assinala&nbsp; o prefeito J\u00fanior da Femac, marcam o in\u00edcio de um novo pacote de investimentos que tamb\u00e9m ser\u00e1 executado em outras importantes vias da regi\u00e3o. \u201cJ\u00e1 renovamos mais de 80% da ilumina\u00e7\u00e3o p\u00fablica da cidade. Somente em tecnologia LED, s\u00e3o mais de 7 mil pontos. Recentemente, por exemplo, executamos um grande trabalho na regi\u00e3o leste e agora estamos complementando com novos investimentos que ir\u00e3o atender vias arteriais importantes, em uma parte de Apucarana que se desenvolveu muito nos \u00faltimos anos\u201d, acentua o prefeito J\u00fanior da Femac, pontuando que al\u00e9m de novos residenciais, a regi\u00e3o viveu expans\u00e3o comercial, industrial e tamb\u00e9m integra o polo universit\u00e1rio, com o presen\u00e7a do campus Apucarana da Universidade Tecnol\u00f3gica Federal do Paran\u00e1 (UTFPR). \u201cIlumina\u00e7\u00e3o mais potente, eficaz e de alta performance. Mais economia, seguran\u00e7a e conforto a todos os moradores, empreendedores, professores e estudantes\u201d, diz o prefeito.<\/p>\n\n\n\n<p>Os trabalhos de campo s\u00e3o executados por uma empresa especializada contrata por licita\u00e7\u00e3o, com supervis\u00e3o da Superintend\u00eancia de Ilumina\u00e7\u00e3o P\u00fablica do Instituto de Desenvolvimento, Pesquisa e Planejamento da Prefeitura de Apucarana (Idepplan), atrav\u00e9s do engenheiro eletricista, Lafayete dos Santos Luz. \u201cNesta empreitada da Rua Denhei Kanashiro come\u00e7amos a partir dos residenciais Ja\u00e7an\u00e3 e Sumatra em dire\u00e7\u00e3o \u00e0 rotat\u00f3ria da UTFPR. Nesse trecho existem lumin\u00e1rias de vapor met\u00e1lico de 250 watts, bastante antigas, que estamos fazendo a substitui\u00e7\u00e3o por lumin\u00e1rias de LED de \u00faltima tecnologia com pot\u00eancia de 150 watts\u201d, confirma Lafayete. Os recursos s\u00e3o oriundos da Contribui\u00e7\u00e3o para Custeio da Ilumina\u00e7\u00e3o P\u00fablica (Cosip).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A ilumina\u00e7\u00e3o p\u00fablica da Rua Denhei Kanashiro, uma das principais vias de liga\u00e7\u00e3o entre bairros na regi\u00e3o leste de Apucarana, ser\u00e1 servida por tecnologia LED. A substitui\u00e7\u00e3o das antigas l\u00e2mpadas vapor met\u00e1lico 250 watts, por novas na pot\u00eancia 150 watts, teve in\u00edcio nesta quarta-feira (28\/02) e \u00e9 uma a\u00e7\u00e3o que integra o plano municipal de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2339","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/2339","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=2339"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/2339\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=2339"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=2339"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=2339"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}