{"id":2319,"date":"2024-02-26T17:45:14","date_gmt":"2024-02-26T17:45:14","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=2319"},"modified":"2024-02-26T17:45:17","modified_gmt":"2024-02-26T17:45:17","slug":"apucaranenses-conseguem-bons-resultados-na-23a-prova-quinzinha","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2024\/02\/26\/apucaranenses-conseguem-bons-resultados-na-23a-prova-quinzinha\/","title":{"rendered":"Apucaranenses conseguem bons resultados na 23\u00aa Prova Quinzinha"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/02\/image-14.png\" alt=\"\" class=\"wp-image-2320\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/02\/image-14.png 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/02\/image-14-600x337.png 600w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/02\/image-14-300x168.png 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/02\/image-14-768x431.png 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Os atletas Yohan Gabriel Brandino de Oliveira, Pedro Henrique Neves Bernardo, Jo\u00e3o Vitor Neves Bernardo, Madelaine Gomes da Silva, Andrelize Vit\u00f3ria Pereira da Cruz e Kethellyn Vit\u00f3ria de Lima, da equipe das categorias de base da Secretaria Municipal de Esportes da Prefeitura de Apucarana, foram destaques em suas categorias nesse s\u00e1bado (24\/02), durante a 23\u00aa Prova Pedestre Quinzinha, realizada em Corn\u00e9lio Proc\u00f3pio. A competi\u00e7\u00e3o tamb\u00e9m foi v\u00e1lida pela abertura do Circuito Sesc de Corridas de Rua 2024.<\/p>\n\n\n\n<p>No masculino, Yohan e Jo\u00e3o Vitor conquistaram a segunda coloca\u00e7\u00e3o nas categorias 14 a 15 anos e 12 a 13 anos, respectivamente. Pedro Henrique obteve a terceira posi\u00e7\u00e3o na categoria 12 a 13 anos. No feminino, Andrelize e Kethellyn ficaram em segundo lugar nas categorias de 14 a 15 anos e 10 a 11 anos, respectivamente. J\u00e1 na prova de 5 quil\u00f4metros, Madelaine foi a segunda colocada na categoria de 16 a 29 anos.<\/p>\n\n\n\n<p>Tamb\u00e9m competiram nesse s\u00e1bado (24\/02) no Norte do Estado, os jovens apucaranenses Adryan Gomes da Silva, Jo\u00e3o Pedro Lima, Jo\u00e3o Miguel, R\u00f4mulo Ramos Monteiro, Ana Clara e N\u00e1thaly Ramos Monteiro.<\/p>\n\n\n\n<p>\u201cComo tem acontecido nos \u00faltimos anos, a equipe de Apucarana mostrou a sua for\u00e7a no atletismo e trouxe v\u00e1rios trof\u00e9us de Corn\u00e9lio Proc\u00f3pio. Os nossos atletas seguem os treinamentos e agora se preparam para o Festival Estadual nas categorias sub-12 e sub-14 que acontecer\u00e1 no dia 2 de mar\u00e7o na pista do Complexo Esportivo Lago\u00e3o, em competi\u00e7\u00e3o que ter\u00e1 o apoio total do prefeito Junior da Femac\u201d, destaca o professor Tom Barros, secret\u00e1rio municipal de Esportes.<\/p>\n\n\n\n<p>Tamb\u00e9m em Corn\u00e9lio Proc\u00f3pio, mas na 46\u00aa edi\u00e7\u00e3o da Prova Pedestre XV de Fevereiro, o paratleta Ubiratan Luis de Oliveira, o Bira, da Secretaria Municipal de Esportes de Apucarana, conquistou a terceira coloca\u00e7\u00e3o na categoria PCD na prova de 5 quil\u00f4metros.<\/p>\n\n\n\n<p><strong>CROSS COUNTRY \u2013&nbsp;<\/strong>Representando a Sele\u00e7\u00e3o Brasileira de Atletismo, a atleta Sabrina Gabrieli Pena, 18, pertencente \u00e0 Secretaria Municipal de Esportes de Apucarana, foi a 12\u00aa colocada na categoria sub-20 na prova de 6 quil\u00f4metros pelo 5\u00ba Campeonato Pan-Americano de Cross Country que aconteceu nesse s\u00e1bado (24\/02) em La Libertad (El Salvador).<\/p>\n\n\n\n<p>Ela, que participou de sua segunda competi\u00e7\u00e3o internacional, fez o tempo de 24\u201911\u2019. A vencedora da prova foi a atleta colombiana Laura Valentina Camargo Cotamo, com o tempo de 21\u201942\u201d.<\/p>\n\n\n\n<p>Mais tr\u00eas brasileiras disputaram a prova em El Salvador. Kauane Rebeca Joaquim (Londrina), Helena Mess Val\u00e9rio (S\u00e3o Jos\u00e9 dos Pinhais) e Luise Rosa Braga (Bras\u00edlia) ficaram em 9\u00ba, 11\u00ba e 13\u00ba lugares, respectivamente. A prova de 6 quil\u00f4metros da categoria sub-20 teve a presen\u00e7a de 21 atletas de seis pa\u00edses.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os atletas Yohan Gabriel Brandino de Oliveira, Pedro Henrique Neves Bernardo, Jo\u00e3o Vitor Neves Bernardo, Madelaine Gomes da Silva, Andrelize Vit\u00f3ria Pereira da Cruz e Kethellyn Vit\u00f3ria de Lima, da equipe das categorias de base da Secretaria Municipal de Esportes da Prefeitura de Apucarana, foram destaques em suas categorias nesse s\u00e1bado (24\/02), durante a 23\u00aa [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2319","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/2319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=2319"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/2319\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=2319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=2319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=2319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}