{"id":2310,"date":"2024-02-26T17:39:57","date_gmt":"2024-02-26T17:39:57","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=2310"},"modified":"2024-02-26T17:40:04","modified_gmt":"2024-02-26T17:40:04","slug":"apucarana-revitaliza-sinalizacao-de-transito-em-30-ruas","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2024\/02\/26\/apucarana-revitaliza-sinalizacao-de-transito-em-30-ruas\/","title":{"rendered":"Apucarana revitaliza sinaliza\u00e7\u00e3o de tr\u00e2nsito em 30 ruas"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/02\/image-11.png\" alt=\"\" class=\"wp-image-2311\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/02\/image-11.png 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/02\/image-11-600x400.png 600w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/02\/image-11-300x200.png 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/02\/image-11-768x512.png 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>A sinaliza\u00e7\u00e3o horizontal de tr\u00e2nsito de ruas e avenidas de v\u00e1rios bairros de Apucarana est\u00e3o recebendo nova pintura. O prefeito J\u00fanior da Femac confirmou nesta ultima sexta-feira (23\/02) que os trabalhos que est\u00e3o sendo executados nesta semana nas avenidas Central do Paran\u00e1 e Santa Catarina, e tamb\u00e9m nas imedia\u00e7\u00f5es do Terminal Rodovi\u00e1rio Jo\u00e3o Boscardin J\u00fanior (rodovi\u00e1ria) integram um cronograma que contempla pelo menos 30 trechos que ir\u00e3o receber a benfeitoria at\u00e9 o final de mar\u00e7o.<\/p>\n\n\n\n<p>As a\u00e7\u00f5es s\u00e3o executadas por uma empresa especializada contratada por licita\u00e7\u00e3o sob a supervis\u00e3o da Superintend\u00eancia de Tr\u00e2nsito, Transporte e Inova\u00e7\u00e3o do Instituto de Desenvolvimento, Pesquisa e Planejamento da Prefeitura de Apucarana (Idepplan). confirmou nesta sexta-feira. \u201cTrata-se de um servi\u00e7o de manuten\u00e7\u00e3o constante que realizamos desde que assumi a prefeitura e visa garantir seguran\u00e7a a todos, tanto condutores como pedestres\u201d, pontua o prefeito J\u00fanior da Femac.<\/p>\n\n\n\n<p>Segundo informa o superintendente do Idepplan e autoridade de tr\u00e2nsito de Apucarana, Carlos Mendes, as a\u00e7\u00f5es atendem a crit\u00e9rios t\u00e9cnicos. \u201cEstamos revitalizando todas as vias da cidade. Um trabalho de rotina que \u00e9 sempre uma cobran\u00e7a do prefeito J\u00fanior da Femac, visando manter a seguran\u00e7a e a fluidez do tr\u00e2nsito em Apucarana. E a gente percebe que nos \u00faltimos cinco anos tivemos grandes avan\u00e7os. Realmente a cidade est\u00e1 cuidada. No setor de tr\u00e2nsito somos uma das que tem uma sinaliza\u00e7\u00e3o mais forte, mais viva. Quem anda pela regi\u00e3o percebe a diferen\u00e7a\u201d, comenta Mendes.<\/p>\n\n\n\n<p>Al\u00e9m das avenidas Central do Paran\u00e1 e Santa Catarina, ele informa que neste m\u00eas j\u00e1 foram executados servi\u00e7os de revitaliza\u00e7\u00e3o da sinaliza\u00e7\u00e3o horizontal nas avenidas marginais Zilda Seixas Amaral e Francisco Kitano (sa\u00edda para Londrina), Avenida Curitiba (Barra Funda), trecho da estrada que liga os distritos de Pirap\u00f3 e Caixa de S\u00e3o Pedro, ruas S\u00e3o Leopoldo e Jos\u00e9 Pelossoni, entre outros locais. \u201cTemos um cronograma extenso at\u00e9 o final de mar\u00e7o, que incluem vias em diversos bairros e distritos. Vamos fazer, por exemplo, a Avenida Itarar\u00e9, a Deolindo Massambani, ruas Capanema, Natividade, S\u00e3o Carlos e Guapuruvu. Na regi\u00e3o central, a Rene Camargo de Azambuja, Cl\u00f3vis da Fonseca, Miguel Simi\u00e3o tamb\u00e9m est\u00e3o no roteiro de trabalho\u201d, informa Mendes, salientando que o investimento \u00e9 integralmente financiado com recursos do munic\u00edpio.<\/p>\n\n\n\n<p>\u201cComo citado, vamos ainda atender aos distritos de Caixa de S\u00e3o Pedro, Pirap\u00f3 e Vila Reis, sinaliza\u00e7\u00e3o nas curvas na estrada velha para Rio Bom, rua Jos\u00e9 Ferragine e H\u00e9lio Brasil. Tamb\u00e9m vamos renovar, onde necess\u00e1rio, a pintura das \u201cesperas para motocicletas\u201d junto a cruzamentos atendidos por sem\u00e1foros\u201d, conclui Carlos Mendes, superintendente de Tr\u00e2nsito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A sinaliza\u00e7\u00e3o horizontal de tr\u00e2nsito de ruas e avenidas de v\u00e1rios bairros de Apucarana est\u00e3o recebendo nova pintura. O prefeito J\u00fanior da Femac confirmou nesta ultima sexta-feira (23\/02) que os trabalhos que est\u00e3o sendo executados nesta semana nas avenidas Central do Paran\u00e1 e Santa Catarina, e tamb\u00e9m nas imedia\u00e7\u00f5es do Terminal Rodovi\u00e1rio Jo\u00e3o Boscardin J\u00fanior [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2310","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/2310","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=2310"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/2310\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=2310"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=2310"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=2310"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}