{"id":2283,"date":"2024-02-15T14:58:45","date_gmt":"2024-02-15T14:58:45","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=2283"},"modified":"2024-02-15T14:58:47","modified_gmt":"2024-02-15T14:58:47","slug":"ivaipora-investe-r620-mil-em-iluminacao-da-estrada-ouro-verde","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2024\/02\/15\/ivaipora-investe-r620-mil-em-iluminacao-da-estrada-ouro-verde\/","title":{"rendered":"Ivaipor\u00e3 investe R$620 mil em ilumina\u00e7\u00e3o da Estrada Ouro Verde"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">O objetivo \u00e9 proporcionar mais visibilidade e seguran\u00e7a na via com a utiliza\u00e7\u00e3o de l\u00e2mpadas LED de alta efici\u00eancia<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"835\" height=\"557\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/02\/Os-investimentos-refletem-o-compromisso-da-adminis-00836514-0-202402151100.webp\" alt=\"\" class=\"wp-image-2284\" style=\"width:517px;height:auto\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/02\/Os-investimentos-refletem-o-compromisso-da-adminis-00836514-0-202402151100.webp 835w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/02\/Os-investimentos-refletem-o-compromisso-da-adminis-00836514-0-202402151100-600x400.webp 600w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/02\/Os-investimentos-refletem-o-compromisso-da-adminis-00836514-0-202402151100-300x200.webp 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/02\/Os-investimentos-refletem-o-compromisso-da-adminis-00836514-0-202402151100-768x512.webp 768w\" sizes=\"(max-width: 835px) 100vw, 835px\" \/><\/figure>\n\n\n\n<p>A seguran\u00e7a dos pedestres, ciclistas, motociclistas, motoristas e produtores rurais \u00e9 uma prioridade para a Prefeitura de\u00a0<a href=\"https:\/\/tnonline.uol.com.br\/tags\/ivaipora?d=1\" target=\"_blank\" rel=\"noreferrer noopener\">Ivaipor\u00e3<\/a>, que est\u00e1 investindo R$620.000,00 na rede de energia da<a href=\"https:\/\/tnonline.uol.com.br\/tags\/estrada-ouro-verde?d=1\" target=\"_blank\" rel=\"noreferrer noopener\">\u00a0Estrada Ouro Verde<\/a>. O objetivo \u00e9 proporcionar mais visibilidade e seguran\u00e7a na via com a utiliza\u00e7\u00e3o de l\u00e2mpadas LED de alta efici\u00eancia.<\/p>\n\n\n\n<p>A Copel est\u00e1 encarregada da instala\u00e7\u00e3o da rede de energia, que compreende postes, cabeamento e transformadores. A previs\u00e3o \u00e9 concluir os trabalhos em 60 dias.<\/p>\n\n\n\n<p>O contrato entre a Prefeitura e a Copel no valor de R$525.000,00 inclui a rede de energia, enquanto a instala\u00e7\u00e3o dos bra\u00e7os e l\u00e2mpadas LED, que foram or\u00e7ados em R$95.000,00, ficar\u00e1 a cargo da equipe de Ilumina\u00e7\u00e3o P\u00fablica da Prefeitura.<\/p>\n\n\n\n<p>Um dos mais beneficiados \u00e9 o ciclista \u2013 especialmente aquele que trabalha durante o dia e gosta de curtir um pedal noturno com a fam\u00edlia ou amigos.<\/p>\n\n\n\n<p>Al\u00e9m deste investimento espec\u00edfico, a Prefeitura vem trabalhando para tornar o sistema de ilumina\u00e7\u00e3o mais eficiente. Em novembro de 2023, foi conclu\u00edda a substitui\u00e7\u00e3o de 4.400 l\u00e2mpadas de vapor de s\u00f3dio por LED na cidade e nos 3 distritos, com investimento de R$2.295.403,70. Adicionalmente, foi implantada uma Usina Fotovoltaica, com investimento de R$1.456.250,00 \u2013 contribuindo para a redu\u00e7\u00e3o da taxa de ilumina\u00e7\u00e3o p\u00fablica em 50%.<\/p>\n\n\n\n<p>Com os R$3.751.653,70 investidos em novembro de 2023 e os R$620.000,00 destinados em fevereiro de 2024, o total de recursos aplicados na melhoria da ilumina\u00e7\u00e3o p\u00fablica em Ivaipor\u00e3 alcan\u00e7a R$4.371.653,70.<\/p>\n\n\n\n<p>O secret\u00e1rio municipal de Obras, Bruno Montoro, afirmou que a ilumina\u00e7\u00e3o adequada torna o tr\u00e1fego mais seguro e beneficia os eventos realizados no Parque de Exposi\u00e7\u00f5es, enquanto o prefeito em exerc\u00edcio Marcelo Reis enfatizou que os investimentos refletem o compromisso da administra\u00e7\u00e3o municipal com a seguran\u00e7a da popula\u00e7\u00e3o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O objetivo \u00e9 proporcionar mais visibilidade e seguran\u00e7a na via com a utiliza\u00e7\u00e3o de l\u00e2mpadas LED de alta efici\u00eancia A seguran\u00e7a dos pedestres, ciclistas, motociclistas, motoristas e produtores rurais \u00e9 uma prioridade para a Prefeitura de\u00a0Ivaipor\u00e3, que est\u00e1 investindo R$620.000,00 na rede de energia da\u00a0Estrada Ouro Verde. O objetivo \u00e9 proporcionar mais visibilidade e seguran\u00e7a [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2283","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/2283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=2283"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/2283\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=2283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=2283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=2283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}