{"id":2252,"date":"2024-02-09T20:14:25","date_gmt":"2024-02-09T20:14:25","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=2252"},"modified":"2024-02-09T20:14:26","modified_gmt":"2024-02-09T20:14:26","slug":"central-de-atendimento-a-dengue-funcionara-na-segunda-e-terca-de-carnaval","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2024\/02\/09\/central-de-atendimento-a-dengue-funcionara-na-segunda-e-terca-de-carnaval\/","title":{"rendered":"Central de Atendimento \u00e0 Dengue funcionar\u00e1 na segunda e ter\u00e7a de carnaval"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/02\/Central-dengue-001-1024x683-1.jpg\" alt=\"\" class=\"wp-image-2253\" style=\"width:498px;height:auto\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/02\/Central-dengue-001-1024x683-1.jpg 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/02\/Central-dengue-001-1024x683-1-600x400.jpg 600w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/02\/Central-dengue-001-1024x683-1-300x200.jpg 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/02\/Central-dengue-001-1024x683-1-768x512.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Com 4.047 atendimentos desde que foi aberta no dia 24 de janeiro, a Central de Atendimento de Combate \u00e0 Dengue, instalada no Gin\u00e1sio Lago\u00e3o, vai funcionar no Carnaval. O servi\u00e7o emergencial estruturado pela prefeitura no hall de entrada da pra\u00e7a esportiva estar\u00e1 \u00e0 disposi\u00e7\u00e3o dos apucaranenses na segunda-feira (12), ter\u00e7a-feira (13) e quarta-feira (14), de 8 horas \u00e0s 22 horas.<\/p>\n\n\n\n<p>Fechadas durante o Carnaval, todas as Unidades B\u00e1sicas de Sa\u00fade retomam o atendimento normal \u00e0 popula\u00e7\u00e3o a partir das 12 horas de quarta-feira. O secret\u00e1rio municipal de sa\u00fade, Em\u00eddio Bachiega, informa que a Unidade B\u00e1sica de Sa\u00fade Bolivar Pav\u00e3o, no Jardim Am\u00e9rica, que se tornou ponto de refer\u00eancia em casos de dengue na cidade, fica aberta todos os dias da semana, entre 8 horas e 22 horas. Isso inclui o pr\u00f3ximo s\u00e1bado (10) e domingo (11) de Carnaval. Outra op\u00e7\u00e3o de atendimento ininterrupto \u00e9 a UPA.<\/p>\n\n\n\n<p>A Central de Atendimento de Combate \u00e0 Dengue montada no hall de entrada da pra\u00e7a esportiva, com capacidade para atender at\u00e9 500 pacientes por dia, come\u00e7a pela ala da recep\u00e7\u00e3o, seguida do setor de triagem e da sala de espera para consulta.<\/p>\n\n\n\n<p>Dando sequencia ao protocolo de atendimento foram instalados 6 consult\u00f3rios m\u00e9dicos que t\u00eam em anexo a sala de soroterapia com 30 cadeiras apropriadas para tratar os pacientes com hidrata\u00e7\u00e3o venosa (soro na veia). Confira os procedimentos realizados no Lago\u00e3o no quadro abaixo.<\/p>\n\n\n\n<p>O superintendente da Aten\u00e7\u00e3o B\u00e1sica da AMS, Odarlone Orente, detalha a equipe de profissionais que atende diariamente na Central de Atendimento da Dengue. \u201cS\u00e3o 6 m\u00e9dicos, 4 enfermeiros, 6 t\u00e9cnicos de enfermagem, 4 administrativos, 2 estagi\u00e1rios de apoio, 2 servi\u00e7os gerais, 1 guarda municipal, e motorista da ambul\u00e2ncia que permanece no local durante todo per\u00edodo de atendimento, de&nbsp; 8 horas \u00e0s 22 horas\u201d, informa Orente.<\/p>\n\n\n\n<p>\u201cEstamos enfrentando uma epidemia de dengue em nossa cidade e a prefeitura est\u00e1 mobilizada na preven\u00e7\u00e3o, combate e tratamento da doen\u00e7a. Nosso mutir\u00e3o de combate a dengue em um m\u00eas coletou 550 caminh\u00f5es de inserv\u00edveis, o que corresponde a quase 3 mil toneladas de materiais que possam acumular \u00e1gua e servir de criadouro do mosquito da dengue. \u00c9 realizado o trabalho de orienta\u00e7\u00e3o pelos agentes de endemias, durante as vistorias nas resid\u00eancias e estamos garantindo atendimento adequado para aquelas pessoas que est\u00e3o com sintomas da dengue\u201d, &nbsp;afirma o prefeito Junior da Femac.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Com 4.047 atendimentos desde que foi aberta no dia 24 de janeiro, a Central de Atendimento de Combate \u00e0 Dengue, instalada no Gin\u00e1sio Lago\u00e3o, vai funcionar no Carnaval. O servi\u00e7o emergencial estruturado pela prefeitura no hall de entrada da pra\u00e7a esportiva estar\u00e1 \u00e0 disposi\u00e7\u00e3o dos apucaranenses na segunda-feira (12), ter\u00e7a-feira (13) e quarta-feira (14), de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2252","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/2252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=2252"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/2252\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=2252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=2252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=2252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}