{"id":224,"date":"2023-08-28T19:17:24","date_gmt":"2023-08-28T19:17:24","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=224"},"modified":"2023-08-28T19:17:25","modified_gmt":"2023-08-28T19:17:25","slug":"queda-de-arvore-provoca-morte-de-homem-na-regiao-veja-detalhes","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2023\/08\/28\/queda-de-arvore-provoca-morte-de-homem-na-regiao-veja-detalhes\/","title":{"rendered":"Queda de \u00e1rvore provoca morte de homem na regi\u00e3o; veja detalhes"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>A v\u00edtima, de 64 anos, realizava a poda de uma \u00e1rvore em frente a sua pr\u00f3pria casa quando o acidente aconteceu<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"408\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/08\/O-IML-de-Apucarana-foi-chamado-00787725-0-202308281449-ScaleDownProportional.webp\" alt=\"\" class=\"wp-image-225\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/08\/O-IML-de-Apucarana-foi-chamado-00787725-0-202308281449-ScaleDownProportional.webp 640w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/08\/O-IML-de-Apucarana-foi-chamado-00787725-0-202308281449-ScaleDownProportional-600x383.webp 600w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/08\/O-IML-de-Apucarana-foi-chamado-00787725-0-202308281449-ScaleDownProportional-300x191.webp 300w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><\/figure>\n\n\n\n<p>Um acidente tr\u00e1gico foi registrado no in\u00edcio da tarde desta segunda-feira, 28 de agosto, em\u00a0<a href=\"https:\/\/tnonline.uol.com.br\/tags\/faxinal?d=1\">Faxinal<\/a>, munic\u00edpio que pertence ao Vale do Iva\u00ed, Paran\u00e1. Um homem de 64 anos morreu depois de ser atingido por uma \u00e1rvore em frente a sua resid\u00eancia, situada pr\u00f3xima \u00e0 Vila Imperatriz, na estrada que d\u00e1 acesso \u00e0 cachoeira do &#8220;Chic\u00e3o&#8221;<\/p>\n\n\n\n<p>A v\u00edtima, identificada como Eliude Wacheski de Souza, realizava a poda da \u00e1rvore com uma motosserra quando foi atingida.<\/p>\n\n\n\n<p>Uma equipe da Unidade B\u00e1sica de Sa\u00fade compareceu ao local para prestar os primeiros cuidados ao idoso, por\u00e9m, nada p\u00f4de ser feito. Eliude sofreu traumas na regi\u00e3o do t\u00f3rax e da cervical, o que o levou \u00e0 morte.<\/p>\n\n\n\n<p>A Pol\u00edcia Civil e Pol\u00edcia Militar tamb\u00e9m foram acionadas para atender a ocorr\u00eancia.<\/p>\n\n\n\n<p>Uma equipe do Instituto M\u00e9dico Legal (IML) de Apucarana foi chamada para recolher o corpo do trabalhador.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A v\u00edtima, de 64 anos, realizava a poda de uma \u00e1rvore em frente a sua pr\u00f3pria casa quando o acidente aconteceu Um acidente tr\u00e1gico foi registrado no in\u00edcio da tarde desta segunda-feira, 28 de agosto, em\u00a0Faxinal, munic\u00edpio que pertence ao Vale do Iva\u00ed, Paran\u00e1. Um homem de 64 anos morreu depois de ser atingido por [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-224","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/224","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=224"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/224\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=224"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=224"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=224"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}