{"id":2143,"date":"2024-01-31T19:31:04","date_gmt":"2024-01-31T19:31:04","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=2143"},"modified":"2024-01-31T19:31:12","modified_gmt":"2024-01-31T19:31:12","slug":"empresas-da-mesma-familia-sao-alvos-da-pf-por-suspeita-de-falsificacao-de-selo-de-inspecao-federal","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2024\/01\/31\/empresas-da-mesma-familia-sao-alvos-da-pf-por-suspeita-de-falsificacao-de-selo-de-inspecao-federal\/","title":{"rendered":"Empresas da mesma fam\u00edlia s\u00e3o alvos da PF por suspeita de falsifica\u00e7\u00e3o de selo de Inspe\u00e7\u00e3o Federal"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/01\/image-40.png\" alt=\"\" class=\"wp-image-2144\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/01\/image-40.png 1000w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/01\/image-40-600x450.png 600w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/01\/image-40-300x225.png 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2024\/01\/image-40-768x576.png 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<p>Oito mandados de busca e apreens\u00e3o foram cumpridos nos endere\u00e7os ligados a quadrilha. Se condenados, pena pode chegar a 29 anos de pris\u00e3o, segundo a PF.<\/p>\n\n\n\n<p>Quatro empresas da mesma fam\u00edlia foram alvos da Pol\u00edcia Federal na manh\u00e3 desta quarta-feira (31), em\u00a0Arapongas, no norte do Paran\u00e1, por suspeita de adulterar e falsificar selo de Inspe\u00e7\u00e3o Federal de produtos aliment\u00edcios para animais.<\/p>\n\n\n\n<p>S\u00e3o oito mandados de busca e apreens\u00e3o nos endere\u00e7os ligados a quadrilha. Ningu\u00e9m foi preso.<\/p>\n\n\n\n<p>Segundo os agentes, as empresas fabricavam e comercializavam suplementos minerais e produtos terap\u00eauticos para alimenta\u00e7\u00e3o de animais de grande porte, como boi e cavalos, sem o registro exigido pelo Minist\u00e9rio da Agricultura e Pecu\u00e1ria.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>&#8220;N\u00e3o atendendo assim aos requisitos m\u00ednimos necess\u00e1rios que garantam a seguran\u00e7a alimentar no processo fabril dos produtos comercializados, com risco \u00e0 sa\u00fade animal e humana&#8221;, afirmou.<\/p>\n<\/blockquote>\n\n\n\n<p>As mercadorias eram comercializadas pela internet com foco em produtores rurais.<\/p>\n\n\n\n<p>Durante as investiga\u00e7\u00f5es, as equipes identificaram que algumas das empresas funcionavam em endere\u00e7os resid\u00eancias, levantando a suspeita de que os donos usavam para sonega\u00e7\u00e3o do Imposto de Renda.<\/p>\n\n\n\n<p>Al\u00e9m disso, h\u00e1 ind\u00edcios de que os produtos sejam de origem estrangeira, importados clandestinamente.<\/p>\n\n\n\n<p>Se condenados, os respons\u00e1veis devem responder por falsifica\u00e7\u00e3o ou adultera\u00e7\u00e3o de produtos aliment\u00edcios, ou medicinais, falsifica\u00e7\u00e3o de selo ou sinal p\u00fablico, podendo chegar a 29 anos de pris\u00e3o, segundo a PF.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oito mandados de busca e apreens\u00e3o foram cumpridos nos endere\u00e7os ligados a quadrilha. Se condenados, pena pode chegar a 29 anos de pris\u00e3o, segundo a PF. Quatro empresas da mesma fam\u00edlia foram alvos da Pol\u00edcia Federal na manh\u00e3 desta quarta-feira (31), em\u00a0Arapongas, no norte do Paran\u00e1, por suspeita de adulterar e falsificar selo de Inspe\u00e7\u00e3o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-2143","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/2143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=2143"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/2143\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=2143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=2143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=2143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}