{"id":203,"date":"2023-08-28T13:34:03","date_gmt":"2023-08-28T13:34:03","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=203"},"modified":"2023-08-28T13:34:05","modified_gmt":"2023-08-28T13:34:05","slug":"melhorias-em-rodovia-facilitam-acesso-ao-aeroporto-e-a-distrito","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2023\/08\/28\/melhorias-em-rodovia-facilitam-acesso-ao-aeroporto-e-a-distrito\/","title":{"rendered":"Melhorias em rodovia facilitam acesso ao aeroporto e a distrito"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\"><strong>Os servi\u00e7os beneficiam os habitantes de Apucarana, o escoamento da produ\u00e7\u00e3o agropecu\u00e1ria de lotes lindeiros \u00e0 PR-532, e usu\u00e1rios do aeroporto<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"835\" height=\"557\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/08\/Melhorias-em-rodovia-facilitam-acesso-ao-aeroporto-00787658-0-202308281026-ScaleDownProportional.webp\" alt=\"\" class=\"wp-image-204\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/08\/Melhorias-em-rodovia-facilitam-acesso-ao-aeroporto-00787658-0-202308281026-ScaleDownProportional.webp 835w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/08\/Melhorias-em-rodovia-facilitam-acesso-ao-aeroporto-00787658-0-202308281026-ScaleDownProportional-600x400.webp 600w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/08\/Melhorias-em-rodovia-facilitam-acesso-ao-aeroporto-00787658-0-202308281026-ScaleDownProportional-300x200.webp 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/08\/Melhorias-em-rodovia-facilitam-acesso-ao-aeroporto-00787658-0-202308281026-ScaleDownProportional-768x512.webp 768w\" sizes=\"(max-width: 835px) 100vw, 835px\" \/><\/figure>\n\n\n\n<p>O Departamento de Estradas de Rodagem do Paran\u00e1 (DER\/PR), autarquia da Secretaria de Infraestrutura e Log\u00edstica (SEIL), est\u00e1 atendendo com melhorias a rodovia de acesso ao Aeroporto Capit\u00e3o Jo\u00e3o Busse e ao distrito de Correia de Freitas, ambos de Apucarana, no Vale do Iva\u00ed.<\/p>\n\n\n\n<p>A PR-532, em um trecho de 10,07 quil\u00f4metros, est\u00e1 contemplada no programa de conserva\u00e7\u00e3o do pavimento Proconserva, iniciando no entroncamento com a BR-376, tamb\u00e9m distrito de Vila Reis, at\u00e9 o final do pavimento da rodovia. Os servi\u00e7os beneficiam os habitantes do munic\u00edpio, o escoamento da produ\u00e7\u00e3o agropecu\u00e1ria de lotes lindeiros \u00e0 PR-532, e usu\u00e1rios do aeroporto.<\/p>\n\n\n\n<p>Os servi\u00e7os incluem remendos profundos, em que a base da pista \u00e9 recomposta com brita graduada simples e macadame. Ap\u00f3s essa etapa \u00e9 aplicada uma nova camada de Concreto Betuminoso Usinado a Quente (CBUQ) para recompor a capa asf\u00e1ltica, seguida por nova sinaliza\u00e7\u00e3o horizontal, com pintura de linhas no eixo e bordos da pista. O programa prev\u00ea, ainda, remendos superficiais, reperfilagem, microrrevestimento e melhorias no sistema de drenagem de \u00e1guas, realizados conforme a necessidade de cada trecho.<\/p>\n\n\n\n<p>Este segmento da PR-532 especificamente pertence ao lote C do Proconserva na Superintend\u00eancia Regional Norte do DER\/PR, que atende 363,84 quil\u00f4metros de rodovias da regi\u00e3o, um investimento de R$ 38,27 milh\u00f5es. O contrato deste lote teve in\u00edcio em abril e tem dura\u00e7\u00e3o de um ano, sendo ent\u00e3o substitu\u00eddo pelo pr\u00f3ximo programa de conserva\u00e7\u00e3o sendo desenvolvido pelo DER\/PR.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os servi\u00e7os beneficiam os habitantes de Apucarana, o escoamento da produ\u00e7\u00e3o agropecu\u00e1ria de lotes lindeiros \u00e0 PR-532, e usu\u00e1rios do aeroporto O Departamento de Estradas de Rodagem do Paran\u00e1 (DER\/PR), autarquia da Secretaria de Infraestrutura e Log\u00edstica (SEIL), est\u00e1 atendendo com melhorias a rodovia de acesso ao Aeroporto Capit\u00e3o Jo\u00e3o Busse e ao distrito de [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-203","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/203","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=203"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/203\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=203"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=203"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=203"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}