{"id":1930,"date":"2023-12-27T12:57:54","date_gmt":"2023-12-27T12:57:54","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=1930"},"modified":"2023-12-27T12:57:55","modified_gmt":"2023-12-27T12:57:55","slug":"rapaz-e-abordado-por-homem-armado-e-tem-celular-roubado","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2023\/12\/27\/rapaz-e-abordado-por-homem-armado-e-tem-celular-roubado\/","title":{"rendered":"Rapaz \u00e9 abordado por homem armado e tem celular roubado"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">A equipe policial realizou patrulhamento pela regi\u00e3o, por\u00e9m o suspeito n\u00e3o foi localizado<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"535\" height=\"400\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/12\/O-crime-aconteceu-na-noite-desta-terca-feira-26-00822474-0-202312270747-ScaleDownProportional.webp\" alt=\"\" class=\"wp-image-1931\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/12\/O-crime-aconteceu-na-noite-desta-terca-feira-26-00822474-0-202312270747-ScaleDownProportional.webp 535w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/12\/O-crime-aconteceu-na-noite-desta-terca-feira-26-00822474-0-202312270747-ScaleDownProportional-300x224.webp 300w\" sizes=\"(max-width: 535px) 100vw, 535px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-right\">Foto por Reprodu\u00e7\u00e3o<\/p>\n\n\n\n<p>Um homem teve o celular roubado na noite desta ter\u00e7a-feira (26) em\u00a0<a href=\"https:\/\/tnonline.uol.com.br\/noticias\/arapongas?d=1\">Arapongas<\/a>. Segundo a v\u00edtima, ele estava trafegando de bicicleta pela Rua Rouxinol, nas proximidades da entrada da Col\u00f4nia Esperan\u00e7a, quando um homem vestindo camisa branca e cal\u00e7a escura, em uma motocicleta Titan 150 de cor preta, o abordou com uma arma de fogo.<\/p>\n\n\n\n<p>Em seguida, o homem deu voz de roubo e pediu o celular da v\u00edtima. Durante o assalto, o suspeito falava que, caso a v\u00edtima n\u00e3o entregasse o celular, ele seria morto. O homem pegou o aparelho celular da marca Samsung, de cor marrom, e fugiu sentido Aricanduva.<\/p>\n\n\n\n<p>A Pol\u00edcia Militar (PM) registrou um boletim de ocorr\u00eancia e orientou a v\u00edtima. A equipe policial realizou patrulhamento pela regi\u00e3o, por\u00e9m o suspeito n\u00e3o foi localizado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A equipe policial realizou patrulhamento pela regi\u00e3o, por\u00e9m o suspeito n\u00e3o foi localizado Foto por Reprodu\u00e7\u00e3o Um homem teve o celular roubado na noite desta ter\u00e7a-feira (26) em\u00a0Arapongas. Segundo a v\u00edtima, ele estava trafegando de bicicleta pela Rua Rouxinol, nas proximidades da entrada da Col\u00f4nia Esperan\u00e7a, quando um homem vestindo camisa branca e cal\u00e7a escura, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1930","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/1930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=1930"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/1930\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=1930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=1930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=1930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}