{"id":1916,"date":"2023-12-26T12:12:40","date_gmt":"2023-12-26T12:12:40","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=1916"},"modified":"2023-12-26T12:12:41","modified_gmt":"2023-12-26T12:12:41","slug":"carro-furtado-e-encontrado-incendiado-na-zona-rural-de-arapongas","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2023\/12\/26\/carro-furtado-e-encontrado-incendiado-na-zona-rural-de-arapongas\/","title":{"rendered":"Carro furtado \u00e9 encontrado incendiado na zona rural de Arapongas"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">PM encontrou ve\u00edculo ainda em chamas na estrada do Novo Mundo, horas depois do furto; carro ficou totalmente destru\u00eddo pelo fogo<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"835\" height=\"557\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/12\/Carro-foi-encontrado-na-estrado-do-Novo-Mundo-00821983-0-202312231108.webp\" alt=\"\" class=\"wp-image-1917\" style=\"width:654px;height:auto\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/12\/Carro-foi-encontrado-na-estrado-do-Novo-Mundo-00821983-0-202312231108.webp 835w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/12\/Carro-foi-encontrado-na-estrado-do-Novo-Mundo-00821983-0-202312231108-600x400.webp 600w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/12\/Carro-foi-encontrado-na-estrado-do-Novo-Mundo-00821983-0-202312231108-300x200.webp 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/12\/Carro-foi-encontrado-na-estrado-do-Novo-Mundo-00821983-0-202312231108-768x512.webp 768w\" sizes=\"(max-width: 835px) 100vw, 835px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-right\">Foto por Reprodu\u00e7\u00e3o PM<\/p>\n\n\n\n<p>Um ve\u00edculo VW\/Gol,\u00a0<a href=\"https:\/\/tnonline.uol.com.br\/tags\/FURTO?d=1\" target=\"_blank\" rel=\"noreferrer noopener\">furtado<\/a>\u00a0em\u00a0<a href=\"https:\/\/tnonline.uol.com.br\/noticias\/arapongas?d=1\" target=\"_blank\" rel=\"noreferrer noopener\">Arapongas<\/a>, no norte do Paran\u00e1, durante a noite desta sexta-feira (22), foi encontrado em chamas pela Pol\u00edcia Militar (PM) j\u00e1 durante a madrugada deste s\u00e1bado (23). O carro estava incendiado na estrada do Novo Mundo, localizada na Zona Rural da cidade.<\/p>\n\n\n\n<p>De acordo com a PM, o carro havia sido furtado na rua rolinhas, no centro da cidade. A propriet\u00e1ria afirmou que deixou o carro estacionado e foi comer um lanche, quando voltou o ve\u00edculo havia sido levado.<\/p>\n\n\n\n<p>Ap\u00f3s fazer um patrulhamento pela Zona Rural da cidade, os agentes localizaram o ve\u00edculo incendiado em meio a uma planta\u00e7\u00e3o de soja. Segundo os policiais, o Corpo de Bombeiros foi acionado para apagar o fogo. O carro, que ficou totalmente destru\u00eddo pelo inc\u00eandio, foi encaminhado para o p\u00e1tio da 22\u00ba SDP de Arapongas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PM encontrou ve\u00edculo ainda em chamas na estrada do Novo Mundo, horas depois do furto; carro ficou totalmente destru\u00eddo pelo fogo Foto por Reprodu\u00e7\u00e3o PM Um ve\u00edculo VW\/Gol,\u00a0furtado\u00a0em\u00a0Arapongas, no norte do Paran\u00e1, durante a noite desta sexta-feira (22), foi encontrado em chamas pela Pol\u00edcia Militar (PM) j\u00e1 durante a madrugada deste s\u00e1bado (23). O carro [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1916","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/1916","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=1916"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/1916\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=1916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=1916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=1916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}