{"id":1902,"date":"2023-12-22T14:28:58","date_gmt":"2023-12-22T14:28:58","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=1902"},"modified":"2023-12-22T14:29:00","modified_gmt":"2023-12-22T14:29:00","slug":"prefeitura-de-apucarana-entrega-carro-para-hospital-da-providencia","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2023\/12\/22\/prefeitura-de-apucarana-entrega-carro-para-hospital-da-providencia\/","title":{"rendered":"Prefeitura de Apucarana entrega carro para Hospital da Provid\u00eancia"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/12\/Entrega-carro-Hospital-Providencia-009-1024x683-1.jpg\" alt=\"\" class=\"wp-image-1903\" style=\"width:576px;height:auto\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/12\/Entrega-carro-Hospital-Providencia-009-1024x683-1.jpg 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/12\/Entrega-carro-Hospital-Providencia-009-1024x683-1-600x400.jpg 600w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/12\/Entrega-carro-Hospital-Providencia-009-1024x683-1-300x200.jpg 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/12\/Entrega-carro-Hospital-Providencia-009-1024x683-1-768x512.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>A Prefeitura de Apucarana repassou (termo de cess\u00e3o) hoje ao Hospital da Provid\u00eancia um carro Ford Fiesta. \u201cEntre tantas outras parcerias que mantemos com o hospital da nossa cidade, estamos cedendo um ve\u00edculo que vai ser de grande ajuda nos trabalhos que a institui\u00e7\u00e3o realiza com idosos e o Programa Elos de Vida\u201d, afirma o prefeito Junior da Femac, no ato de entrega da chave a diretora geral do Provid\u00eancia, irm\u00e3 Geovana Ramos.<\/p>\n\n\n\n<p>Programa Elos de Vida que presta o apoio necess\u00e1rio \u00e0s mam\u00e3es adolescentes e\/ou carentes e conta com o apoio e parceria da Autarquia Municipal de Sa\u00fade, atrav\u00e9s da Escola da Gestante e da Secretaria de Assist\u00eancia Social.<\/p>\n\n\n\n<p>\u201cAgrade\u00e7o a sensibilidade do prefeito Junior da Femac, de mais uma vez apoiar nosso hospital. Vamos utilizar esse carro, por exemplo, para realizar as visitas de acompanhamento das pessoas atendidas em nossos projetos sociais como o Elos de Vida e Projeto Social Boa Idade 60+\u201d, informa irm\u00e3 Geovana.<\/p>\n\n\n\n<p>O Projeto Social Boa Idade 60+ oferta servi\u00e7os de conviv\u00eancia com tarefas comunit\u00e1rias e fortalecimento de v\u00ednculo para a pessoa idosa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Prefeitura de Apucarana repassou (termo de cess\u00e3o) hoje ao Hospital da Provid\u00eancia um carro Ford Fiesta. \u201cEntre tantas outras parcerias que mantemos com o hospital da nossa cidade, estamos cedendo um ve\u00edculo que vai ser de grande ajuda nos trabalhos que a institui\u00e7\u00e3o realiza com idosos e o Programa Elos de Vida\u201d, afirma o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1902","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/1902","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=1902"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/1902\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=1902"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=1902"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=1902"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}