{"id":1807,"date":"2023-12-18T13:32:13","date_gmt":"2023-12-18T13:32:13","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=1807"},"modified":"2023-12-18T13:32:14","modified_gmt":"2023-12-18T13:32:14","slug":"recurso-da-itaipu-garante-asfalto-em-estrada-que-interliga-vilas-rurais-em-apucarana","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2023\/12\/18\/recurso-da-itaipu-garante-asfalto-em-estrada-que-interliga-vilas-rurais-em-apucarana\/","title":{"rendered":"Recurso da Itaipu garante asfalto em estrada que interliga vilas rurais em Apucarana"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/12\/ESTRADA-RURAL-PROFETA-4-1024x683-1.jpg\" alt=\"\" class=\"wp-image-1808\" style=\"width:547px;height:auto\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/12\/ESTRADA-RURAL-PROFETA-4-1024x683-1.jpg 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/12\/ESTRADA-RURAL-PROFETA-4-1024x683-1-600x400.jpg 600w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/12\/ESTRADA-RURAL-PROFETA-4-1024x683-1-300x200.jpg 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/12\/ESTRADA-RURAL-PROFETA-4-1024x683-1-768x512.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Apucarana \u00e9 um dos munic\u00edpios contemplados no edital do Programa Itaipu Mais que Energia, a maior iniciativa de apoio a projetos sociais, ambientais e de infraestrutura da hist\u00f3ria da empresa. Com isso, a Itaipu Binacional ir\u00e1 repassar cerca de R$2 milh\u00f5es a Prefeitura de Apucarana que, somados \u00e0 contrapartida municipal prevista no conv\u00eanio (R$361.308.000,00), totalizam investimentos na ordem de R$2.408.720,00, que s\u00e3o aplicados em obras de pavimenta\u00e7\u00e3o, recupera\u00e7\u00e3o de nascentes e gera\u00e7\u00e3o de energia fotovoltaica.<\/p>\n\n\n\n<p>O repasse do cr\u00e9dito aos cofres municipais, que ser\u00e1 feito pela Caixa Econ\u00f4mica Federal, parceira de Itaipu no programa, foi referendado nesta quinta-feira (15\/12), em sess\u00f5es extraordin\u00e1rias, pela C\u00e2mara Municipal de Vereadores. A maior parte do dinheiro, na ordem de R$1,6 milh\u00e3o, ser\u00e1 utilizada para a primeira etapa de pavimenta\u00e7\u00e3o asf\u00e1ltica da estrada que interliga as vilas rurais Manoel Piassa da Silva Sobrinho, no Distrito de Vila Reis, e Nova Ukr\u00e2nia, junto ao Contorno Sul.<\/p>\n\n\n\n<p>Segundo destaca o prefeito J\u00fanior da Femac, nos \u00faltimos anos moradores da Vila Reis adotaram a rota rural, que \u00e9 um caminho mais curto para o centro da cidade. \u201cTemos executado diversas melhorias nos cerca de cinco quil\u00f4metros que interligam essas duas importantes comunidades de Apucarana. No ano passado, por exemplo, aplicamos espessa camada de res\u00edduo asf\u00e1ltico, que possibilitou uma maior trafegabilidade, e agora, atrav\u00e9s do programa da Itaipu Binacional, vamos poder pavimentar um grande trecho\u201d, assegurou o prefeito.<\/p>\n\n\n\n<p>O deputado estadual Arilson Chiorato, que teve atua\u00e7\u00e3o decisiva para apresentar o Programa \u201cItaipu Mais que Energia\u201d em Apucarana, anunciou ao prefeito Junior da Femac, que os recursos da Binacional Itaipu, foram depositados, nesta sexta-feira (15), em conta espec\u00edfica da Prefeitura de Apucarana, na Caixa Econ\u00f4mica Federal. \u201cPela primeira vez, consegui a inclus\u00e3o de Apucarana na libera\u00e7\u00e3o de recursos pela Itaipu. Esse recurso garante a pavimenta\u00e7\u00e3o de importante estrada rural da Vila Reis com a regi\u00e3o do Contorno Sul da cidade; e tamb\u00e9m a instala\u00e7\u00e3o de uma usina foto-voltaica, para a produ\u00e7\u00e3o de energia limpa\u201d, assinala Arilson Chioratto.<\/p>\n\n\n\n<p>Segundo esclarece superintendente de Obras da Prefeitura de Apucarana, engenheira civil Carolina Moreira de Souza, o projeto aprovado junto \u00e0 Itaipu Binacional \u00e9 relativo \u00e0 primeira etapa de pavimenta\u00e7\u00e3o, contemplando metade do trajeto entre as comunidades rurais. \u201cA pavimenta\u00e7\u00e3o ser\u00e1 na modalidade de Tratamento Superficial Triplo (TST), partindo da Vila Reis, e abranger\u00e1 um trecho de 2,4 quil\u00f4metros (2.400 metros), entre a vila rural e a ponte do Ribeir\u00e3o Bigua\u00e7u\u201d, detalha a engenheira. Segundo ela, com o conv\u00eanio referendado pelos vereadores, a prefeitura poder\u00e1 dar andamento ao processo de licita\u00e7\u00e3o da obra.<\/p>\n\n\n\n<p>L\u00edder pol\u00edtico na regi\u00e3o, o vereador Toninho Garcia assinala que trata-se de uma reivindica\u00e7\u00e3o antiga da popula\u00e7\u00e3o de Vila Reis, visando melhor estruturar a rota alternativa de acesso \u00e0 cidade. Segundo ele, com a pavimenta\u00e7\u00e3o asf\u00e1ltica da estrada rural, que fica pr\u00f3xima de outras \u00e1reas industriais do munic\u00edpio, naturalmente, ser\u00e3o viabilizadas novas \u00e1reas para instala\u00e7\u00e3o de ind\u00fastrias. \u201cEste projeto, que vem recebendo apoio do prefeito Junior da Femac, pode contribuir na gera\u00e7\u00e3o de emprego e renda em Apucarana\u201d, ressalta o vereador, que representa o distrito de Vila Reis.<\/p>\n\n\n\n<p>Ainda dentro do plano de a\u00e7\u00e3o de Apucarana aprovado pelo Programa Mais que energia da Itaipu Binacional, est\u00e3o investimentos relacionados ao manejo de \u00e1gua e solo, e energia renov\u00e1vel. \u201cDentro do conv\u00eanio, de R$783 mil est\u00e3o destinados a a\u00e7\u00f5es de recupera\u00e7\u00e3o de nascentes, biodigestores e viabiliza\u00e7\u00e3o de sistema de gera\u00e7\u00e3o fotovoltaica (usina solar).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apucarana \u00e9 um dos munic\u00edpios contemplados no edital do Programa Itaipu Mais que Energia, a maior iniciativa de apoio a projetos sociais, ambientais e de infraestrutura da hist\u00f3ria da empresa. Com isso, a Itaipu Binacional ir\u00e1 repassar cerca de R$2 milh\u00f5es a Prefeitura de Apucarana que, somados \u00e0 contrapartida municipal prevista no conv\u00eanio (R$361.308.000,00), totalizam [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1807","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/1807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=1807"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/1807\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=1807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=1807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=1807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}