{"id":1656,"date":"2023-12-08T13:18:46","date_gmt":"2023-12-08T13:18:46","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=1656"},"modified":"2023-12-08T13:18:47","modified_gmt":"2023-12-08T13:18:47","slug":"espetaculos-de-violao-e-bateria-lotam-cine-teatro-fenix","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2023\/12\/08\/espetaculos-de-violao-e-bateria-lotam-cine-teatro-fenix\/","title":{"rendered":"Espet\u00e1culos de viol\u00e3o e bateria lotam Cine Teatro F\u00eanix"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/12\/20231206_201135-1024x576-1.jpg\" alt=\"\" class=\"wp-image-1657\" style=\"width:677px;height:auto\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/12\/20231206_201135-1024x576-1.jpg 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/12\/20231206_201135-1024x576-1-600x338.jpg 600w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/12\/20231206_201135-1024x576-1-300x169.jpg 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/12\/20231206_201135-1024x576-1-768x432.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Na quarta noite de espet\u00e1culos did\u00e1ticos de final ano da Escola Municipal de Artes, alunos de bateria e viol\u00e3o se apresentaram ontem (6) no palco do Cine Teatro F\u00eanix. O p\u00fablico, que mais uma vez lotou o local, foi presenteado com uma grande noite musical.<\/p>\n\n\n\n<p>Cerca de 250 apucaranenses, de todas as idades, frequentam as aulas de viol\u00e3o oferecidas gratuitamente pela prefeitura de Apucarana. Eles proporcionaram apresenta\u00e7\u00f5es com variado repert\u00f3rio, incluindo g\u00eanero sertanejo com direito a berrante.<\/p>\n\n\n\n<p>A maioria das m\u00fasicas ao viol\u00e3o foi acompanhada pelos alunos de bateria da Escola Municipal de Artes. Encerrando a noite, a apresenta\u00e7\u00e3o foi protagonizada por alunos da bateria, mostrando o quanto j\u00e1 dominam o instrumento.<\/p>\n\n\n\n<p>O prefeito Junior da Femac, que prestigiou os espet\u00e1culos, parabenizou os alunos e garantiu o incentivo da sua gest\u00e3o as artes e cultura. A Escola Municipal de Artes \u00e9 um orgulho para nossa administra\u00e7\u00e3o e para nossa cidade\u201d, afirmou Junior da Femac.<\/p>\n\n\n\n<p>Com entrada franca e in\u00edcio \u00e0s 20 horas, os oito dias de espet\u00e1culos do Festival das Artes 2023 tiveram in\u00edcio na sexta-feira, com apresenta\u00e7\u00f5es do coral municipal, de viol\u00e3o e de bateria. J\u00e1 na programa\u00e7\u00e3o do \u00faltimo s\u00e1bado os alunos de piano foram os artistas da noite. Na segunda-feira, depois de um novo recital de piano, foi a vez dos alunos de violino proporcionarem um belo espet\u00e1culo.<\/p>\n\n\n\n<p>Amanh\u00e3 e sexta-feira sobem ao palco os alunos de teatro da Escola Municipal de Artes. No primeiro dia acontece a Mostra de Teatro Juvenil e na noite seguinte Mostra de Teatro Adulto.<\/p>\n\n\n\n<p>O s\u00e1bado (9) e domingo (10) ser\u00e3o reservados para apresenta\u00e7\u00f5es dos alunos de dan\u00e7a, com espet\u00e1culo de Ballet Juvenil Adulto e espet\u00e1culo de ballet infantil, respectivamente.<\/p>\n\n\n\n<p>Festival das Artes 2023 da Escola Municipal de Artes re\u00fane apresenta\u00e7\u00f5es protagonizadas por cerca de 2 mil alunos que frequentam aulas de que m\u00fasica, dan\u00e7a e teatro oferecidas gratuitamente pela Prefeitura de Apucarana.<\/p>\n\n\n\n<p>A Escola Municipal de Artes, da Prefeitura de Apucarana, por meio da Secretaria Municipal da Promo\u00e7\u00e3o Art\u00edstica, Cultural e Tur\u00edstica (Promatur), ministra aulas gratuitamente na Casa da Cultura, anexa ao Cine Teatro F\u00eanix.<\/p>\n\n\n\n<p>\u201cA Escola Municipal de Artes \u00e9 um orgulho para nossa cidade. Um investimento da administra\u00e7\u00e3o municipal que tem um retorno de encher os olhos. As apresenta\u00e7\u00f5es que estamos assistindo comprovam o alcance desse programa na vida de tantos apucaranenses. Parab\u00e9ns a cada um que subiu neste palco e nos emocionou com um grande espet\u00e1culo\u201d, afirma o prefeito Junior da Femac.<\/p>\n\n\n\n<p>A Escola Municipal de Artes, da Prefeitura de Apucarana, por meio da Secretaria Municipal da Promo\u00e7\u00e3o Art\u00edstica, Cultural e Tur\u00edstica (Promatur), ministra aulas gratuitamente na Casa da Cultura, anexa ao Cine Teatro F\u00eanix.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na quarta noite de espet\u00e1culos did\u00e1ticos de final ano da Escola Municipal de Artes, alunos de bateria e viol\u00e3o se apresentaram ontem (6) no palco do Cine Teatro F\u00eanix. O p\u00fablico, que mais uma vez lotou o local, foi presenteado com uma grande noite musical. Cerca de 250 apucaranenses, de todas as idades, frequentam as [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1656","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/1656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=1656"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/1656\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=1656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=1656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=1656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}