{"id":1451,"date":"2023-11-28T18:14:07","date_gmt":"2023-11-28T18:14:07","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=1451"},"modified":"2023-11-28T18:14:07","modified_gmt":"2023-11-28T18:14:07","slug":"prefeito-pede-participacao-de-apucaranenses-em-consulta-on-line-sobre-seguranca-publica","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2023\/11\/28\/prefeito-pede-participacao-de-apucaranenses-em-consulta-on-line-sobre-seguranca-publica\/","title":{"rendered":"Prefeito pede participa\u00e7\u00e3o de apucaranenses em consulta on-line sobre seguran\u00e7a p\u00fablica"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/11\/Seguranca-3-1024x683-1.jpg\" alt=\"\" class=\"wp-image-1452\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/11\/Seguranca-3-1024x683-1.jpg 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/11\/Seguranca-3-1024x683-1-600x400.jpg 600w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/11\/Seguranca-3-1024x683-1-300x200.jpg 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/11\/Seguranca-3-1024x683-1-768x512.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>O prefeito Junior da Femac est\u00e1 conclamando a popula\u00e7\u00e3o de Apucarana a participar at\u00e9 o dia 3 de dezembro da consulta on-line para constru\u00e7\u00e3o do Plano Estadual de Seguran\u00e7a P\u00fablica e Defesa Social do Paran\u00e1 (PESPDS 2024-2034). A iniciativa \u00e9 da Secretaria Estadual de Seguran\u00e7a P\u00fablica do Estado do Paran\u00e1, com o apoio metodol\u00f3gico do Sistema Fiep.<\/p>\n\n\n\n<p>\u201cEstamos divulgando o link&nbsp;<a href=\"https:\/\/observatorios.fiepr.org.br\/obsurvey\/planosegurancapr\">https:\/\/observatorios.fiepr.org.br\/obsurvey\/planosegurancapr<\/a>&nbsp;para os apucaranenses responderem a consulta sobre esse importante tema da nossa sociedade que \u00e9 a seguran\u00e7a. Queremos que Apucarana abrace essa iniciativa do Governo do Estado. \u00c9 uma consulta abrangente e autoexplicativa. A administra\u00e7\u00e3o municipal far\u00e1 sua parte colocando seu time de servidores para responder\u201d, afirma Junior da Femac.<\/p>\n\n\n\n<p>A pesquisa \u00e9 aplicada em 5 eixos: Criminalidade, Proatividade, Sistema Prisional, Atividades de Emerg\u00eancia e Preven\u00e7\u00e3o e &nbsp;Valoriza\u00e7\u00e3o do Profissional de Seguran\u00e7a P\u00fablica. Ao realizar a consulta para constru\u00e7\u00e3o do Plano Estadual de Seguran\u00e7a P\u00fablica e Defesa Social do Paran\u00e1 o Governo do Estado tem como meta fazer do \u201cParan\u00e1 um estado onde as pessoas se sintam seguras e os servi\u00e7os de seguran\u00e7a p\u00fablica<br>sejam reconhecidos pela efetividade das a\u00e7\u00f5es integradas de preven\u00e7\u00e3o, enfrentamento e controle.\u201d<\/p>\n\n\n\n<p>As informa\u00e7\u00f5es coletadas ser\u00e3o tratadas e consolidadas, exclusivamente pela equipe do Observat\u00f3rio Sistema FIEP, garantindo o anonimato dos participantes. Os resultados ser\u00e3o apresentados de forma agregada sem qualquer identifica\u00e7\u00e3o individual.<\/p>\n\n\n\n<p>A presidente Conselho Comunit\u00e1rio de Seguran\u00e7a de Apucarana (Conseg Apucarana), Ana Maria Schmidt, acompanhada do tesoureiro da entidade Nelson Telles do Prado, e do coordenador de seguran\u00e7a junto ao gabinete do prefeito Junior da Femac, Marcos Jos\u00e9&nbsp;Facio se reuniu com o prefeito Junior da Femac na tarde de hoje para pedir apoio na divulga\u00e7\u00e3o da consulta on-line do Plano Decenal Estadual de Seguran\u00e7a P\u00fablica<\/p>\n\n\n\n<p>\u201cA consulta publica on-line traz a possibilidade da participa\u00e7\u00e3o da popula\u00e7\u00e3o, do controle social desta pol\u00edtica p\u00fablica essencial para todos os paranaenses. Apesar do plano ser em n\u00edvel de estado, Apucarana ser\u00e1 impactada com as decis\u00f5es. Desta forma quanto mais pessoas puderem participar a pensar o Estado, mais ajudaremos a seguran\u00e7a no nosso munic\u00edpio\u201d, afirma Ana Maria.<\/p>\n\n\n\n<p><strong>Responda a consulta at\u00e9 3 de dezembro pelo link&nbsp;<a href=\"https:\/\/observatorios.fiepr.org.br\/obsurvey\/planosegurancapr\">https:\/\/observatorios.fiepr.org.br\/obsurvey\/planosegurancapr<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O prefeito Junior da Femac est\u00e1 conclamando a popula\u00e7\u00e3o de Apucarana a participar at\u00e9 o dia 3 de dezembro da consulta on-line para constru\u00e7\u00e3o do Plano Estadual de Seguran\u00e7a P\u00fablica e Defesa Social do Paran\u00e1 (PESPDS 2024-2034). A iniciativa \u00e9 da Secretaria Estadual de Seguran\u00e7a P\u00fablica do Estado do Paran\u00e1, com o apoio metodol\u00f3gico do [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1451","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/1451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=1451"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/1451\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=1451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=1451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=1451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}