{"id":1448,"date":"2023-11-28T18:11:57","date_gmt":"2023-11-28T18:11:57","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=1448"},"modified":"2023-11-28T18:11:58","modified_gmt":"2023-11-28T18:11:58","slug":"escolas-recebem-materiais-didaticos-para-o-ano-letivo-de-2024","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2023\/11\/28\/escolas-recebem-materiais-didaticos-para-o-ano-letivo-de-2024\/","title":{"rendered":"Escolas recebem materiais did\u00e1ticos para o ano letivo de 2024"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"685\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/11\/ANO-LETIVO-12-1024x685-1.jpg\" alt=\"\" class=\"wp-image-1449\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/11\/ANO-LETIVO-12-1024x685-1.jpg 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/11\/ANO-LETIVO-12-1024x685-1-600x401.jpg 600w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/11\/ANO-LETIVO-12-1024x685-1-300x201.jpg 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/11\/ANO-LETIVO-12-1024x685-1-768x514.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>A Autarquia Municipal de Educa\u00e7\u00e3o come\u00e7ou a encaminhar, hoje (28\/11), aos 24 centros infantis (CMEIs) e 36 escolas da sua rede, os materiais did\u00e1ticos que ser\u00e3o utilizados pelos estudantes apucaranenses no ano letivo de 2024. Os principais itens repassados s\u00e3o cadernos de linguagem, aritm\u00e9tica e desenho, agenda, l\u00e1pis preto, l\u00e1pis de cor, borracha, apontador, tesoura, cola, estojo, pastas, canetas, tinta guache, giz de cera e massa de modelar.<\/p>\n\n\n\n<p>Desde 2013, os 12,5 mil estudantes matriculados na rede municipal de educa\u00e7\u00e3o recebem materiais escolares, gratuitamente, da Prefeitura de Apucarana. \u201cA iniciativa visa aliviar o or\u00e7amento das fam\u00edlias e garantir que todas as crian\u00e7as tenham materiais adequados para estudar. O repasse dos produtos com dois meses de anteced\u00eancia aos CMEIs e Escolas \u00e9 resultado do excelente planejamento feito pelas nossas equipes pedag\u00f3gica, financeira, licitat\u00f3ria e operacional. J\u00e1 no primeiro dia de aulas, os estudantes estar\u00e3o com todos os materiais escolares em suas m\u00e3os,\u201d disse o prefeito Junior da Femac.<\/p>\n\n\n\n<p>A secret\u00e1ria de educa\u00e7\u00e3o, Marli Fernandes, destacou a qualidade dos materiais escolares. \u201cN\u00f3s exigimos sempre que as empresas, vencedoras da licita\u00e7\u00e3o, entreguem produtos sem defeitos e com boa durabilidade. Todos os itens passam por um rigoroso controle de qualidade feito pela nossa equipe antes de chegarem aos estudantes. Em Apucarana, a educa\u00e7\u00e3o \u00e9 prioridade na atual administra\u00e7\u00e3o municipal,\u201d acrescentou.<\/p>\n\n\n\n<p>Os estudantes da rede municipal de educa\u00e7\u00e3o tamb\u00e9m devem receber novos uniformes j\u00e1 no primeiro dia do ano letivo de 2024.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Autarquia Municipal de Educa\u00e7\u00e3o come\u00e7ou a encaminhar, hoje (28\/11), aos 24 centros infantis (CMEIs) e 36 escolas da sua rede, os materiais did\u00e1ticos que ser\u00e3o utilizados pelos estudantes apucaranenses no ano letivo de 2024. Os principais itens repassados s\u00e3o cadernos de linguagem, aritm\u00e9tica e desenho, agenda, l\u00e1pis preto, l\u00e1pis de cor, borracha, apontador, tesoura, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1448","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/1448","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=1448"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/1448\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=1448"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=1448"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=1448"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}