{"id":1313,"date":"2023-11-14T13:01:19","date_gmt":"2023-11-14T13:01:19","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=1313"},"modified":"2023-11-14T13:01:20","modified_gmt":"2023-11-14T13:01:20","slug":"dois-adultos-sao-presos-apos-furto-de-kit-churrasco-em-arapongas","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2023\/11\/14\/dois-adultos-sao-presos-apos-furto-de-kit-churrasco-em-arapongas\/","title":{"rendered":"Dois adultos s\u00e3o presos ap\u00f3s furto de \u2018kit churrasco\u2019 em Arapongas"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Junto com os adultos estavam dois menores de idade que foram apreendidos; grupo furtou carnes e outros itens de lojas da cidade<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"837\" height=\"557\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/11\/Itens-apreendidos-foram-e-encaminhado-para-a-deleg-00810037-0-202311140933-ScaleDownProportional.webp\" alt=\"\" class=\"wp-image-1314\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/11\/Itens-apreendidos-foram-e-encaminhado-para-a-deleg-00810037-0-202311140933-ScaleDownProportional.webp 837w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/11\/Itens-apreendidos-foram-e-encaminhado-para-a-deleg-00810037-0-202311140933-ScaleDownProportional-600x399.webp 600w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/11\/Itens-apreendidos-foram-e-encaminhado-para-a-deleg-00810037-0-202311140933-ScaleDownProportional-300x200.webp 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/11\/Itens-apreendidos-foram-e-encaminhado-para-a-deleg-00810037-0-202311140933-ScaleDownProportional-768x511.webp 768w\" sizes=\"(max-width: 837px) 100vw, 837px\" \/><\/figure>\n\n\n\n<p>Dois adultos foram presos e dois adolescentes apreendidos ap\u00f3s cometerem furtos em com\u00e9rcios da \u00e1rea central de\u00a0<a href=\"https:\/\/tnonline.uol.com.br\/noticias\/arapongas?d=1\" target=\"_blank\" rel=\"noreferrer noopener\">Arapongas<\/a>\u00a0na tarde desta segunda-feira (13). Eles s\u00e3o suspeitos de furtarem carnes e diversos outros itens, como lata de tinta spray, eletr\u00f4nicos, cadeados e outras utens\u00edlios de lojas da cidade.<\/p>\n\n\n\n<p>Entre os adultos estavam um homem de 36 anos e uma mulher de 30. J\u00e1 os adolescentes eram um menino de 13 anos e uma menina de 16. Segundo os agentes, um Guarda Municipal de folga avistou quando um funcion\u00e1rio de uma das lojas estava correndo atr\u00e1s de alguns suspeitos.<\/p>\n\n\n\n<p>CONTINUA AP\u00d3S PUBLICIDADE<\/p>\n\n\n\n<p>No entanto, o adulto suspeito foi detido enquanto tentava entrar dentro de um carro. Em seguida, os outros tr\u00eas envolvidos foram avistados correndo em dire\u00e7\u00e3o a linha f\u00e9rrea. Eles foram alcan\u00e7ados e receberam voz de abordagem, segundo os agentes. Com eles estavam outros itens furtados.<\/p>\n\n\n\n<p>Os quatro foram encaminhados para a delegacia de Arapongas. Segundo os GMs, o conselho tutelar tamb\u00e9m foi acionado por conta dos menores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Junto com os adultos estavam dois menores de idade que foram apreendidos; grupo furtou carnes e outros itens de lojas da cidade Dois adultos foram presos e dois adolescentes apreendidos ap\u00f3s cometerem furtos em com\u00e9rcios da \u00e1rea central de\u00a0Arapongas\u00a0na tarde desta segunda-feira (13). Eles s\u00e3o suspeitos de furtarem carnes e diversos outros itens, como lata [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1313","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/1313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=1313"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/1313\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=1313"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=1313"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=1313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}