{"id":1294,"date":"2023-11-13T14:27:33","date_gmt":"2023-11-13T14:27:33","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=1294"},"modified":"2023-11-13T14:27:35","modified_gmt":"2023-11-13T14:27:35","slug":"prf-apreende-em-apucarana-carreta-carregada-com-cigarros-do-paraguai","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2023\/11\/13\/prf-apreende-em-apucarana-carreta-carregada-com-cigarros-do-paraguai\/","title":{"rendered":"PRF apreende em Apucarana carreta carregada com cigarros do Paraguai"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Foram encontrados 67 mil ma\u00e7os de cigarro de origem paraguaia<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"891\" height=\"501\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/11\/A-apreensao-foi-na-manha-deste-sabado-11-00809627-0-202311121858.webp\" alt=\"\" class=\"wp-image-1295\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/11\/A-apreensao-foi-na-manha-deste-sabado-11-00809627-0-202311121858.webp 891w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/11\/A-apreensao-foi-na-manha-deste-sabado-11-00809627-0-202311121858-600x337.webp 600w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/11\/A-apreensao-foi-na-manha-deste-sabado-11-00809627-0-202311121858-300x169.webp 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/11\/A-apreensao-foi-na-manha-deste-sabado-11-00809627-0-202311121858-768x432.webp 768w\" sizes=\"(max-width: 891px) 100vw, 891px\" \/><\/figure>\n\n\n\n<p>Um homem de 37 anos foi preso na manh\u00e3 deste s\u00e1bado (11), por uma equipe da Pol\u00edcia Rodovi\u00e1ria Federal que realizava ronda pela BR-376, pr\u00f3ximo ao km 328, quando visualizou uma carreta de cor azul em atitude suspeita e procedeu \u00e0 abordagem.<\/p>\n\n\n\n<p>Durante a abordagem, o motorista, morador da cidade de Ponta Grossa &#8211; PR, apresentava sinais de nervosismo e ao ser questionado declinou que transportava uma carga de cigarros de origem paraguaia em meio a carga de soja, sendo esta de origem l\u00edcita. O condutor informou que pegou o cigarro em uma cidade do interior do Mato Grosso do Sul e entregaria na cidade de Paranagu\u00e1-PR.<\/p>\n\n\n\n<p>Ao verificar a carga, a equipe PRF da Unidade Operacional de Apucarana encontrou 67 mil ma\u00e7os de cigarro de origem paraguaia (a ser contabilizado na Receita Federal).<\/p>\n\n\n\n<p>O condutor foi preso em flagrante pelo crime de contrabando, sendo encaminhado para a Delegacia da Pol\u00edcia Federal em Londrina, o ve\u00edculo juntamente com a carga foi encaminhado para a Receita Federal em Londrina.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Foram encontrados 67 mil ma\u00e7os de cigarro de origem paraguaia Um homem de 37 anos foi preso na manh\u00e3 deste s\u00e1bado (11), por uma equipe da Pol\u00edcia Rodovi\u00e1ria Federal que realizava ronda pela BR-376, pr\u00f3ximo ao km 328, quando visualizou uma carreta de cor azul em atitude suspeita e procedeu \u00e0 abordagem. Durante a abordagem, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1294","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/1294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=1294"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/1294\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=1294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=1294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=1294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}