{"id":1257,"date":"2023-11-08T12:42:02","date_gmt":"2023-11-08T12:42:02","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=1257"},"modified":"2023-11-08T12:42:03","modified_gmt":"2023-11-08T12:42:03","slug":"idosa-tem-fratura-no-femur-apos-ser-atropelada-por-onibus-em-apucarana","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2023\/11\/08\/idosa-tem-fratura-no-femur-apos-ser-atropelada-por-onibus-em-apucarana\/","title":{"rendered":"Idosa tem fratura no f\u00eamur ap\u00f3s ser atropelada por \u00f4nibus em Apucarana"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">V\u00edtima de 73 anos foi atropelada enquanto estava atravessando a faixa de pedestre ao lado do terminal; idosa tamb\u00e9m teve fraturas expostas<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"891\" height=\"501\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/11\/Mulher-foi-encaminhada-para-o-Hospital-da-Providen-00808171-0-202311080852-ScaleDownProportional.webp\" alt=\"\" class=\"wp-image-1258\" style=\"aspect-ratio:1.778443113772455;width:761px;height:auto\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/11\/Mulher-foi-encaminhada-para-o-Hospital-da-Providen-00808171-0-202311080852-ScaleDownProportional.webp 891w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/11\/Mulher-foi-encaminhada-para-o-Hospital-da-Providen-00808171-0-202311080852-ScaleDownProportional-600x337.webp 600w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/11\/Mulher-foi-encaminhada-para-o-Hospital-da-Providen-00808171-0-202311080852-ScaleDownProportional-300x169.webp 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/11\/Mulher-foi-encaminhada-para-o-Hospital-da-Providen-00808171-0-202311080852-ScaleDownProportional-768x432.webp 768w\" sizes=\"(max-width: 891px) 100vw, 891px\" \/><\/figure>\n\n\n\n<p>Uma idosa de 73 anos teve uma fratura no f\u00eamur, al\u00e9m de outras fraturas expostas, ap\u00f3s ser atropelada por um \u00f4nibus do transporte coletivo na manh\u00e3 desta quarta-feira (8) em\u00a0<a rel=\"noreferrer noopener\" href=\"https:\/\/tnonline.uol.com.br\/noticias\/apucarana?d=1\" target=\"_blank\">Apucarana<\/a>, no norte do Paran\u00e1. O acidente aconteceu enquanto a mulher estava atravessando a rua em uma uma faixa de pedestre ao lado do Terminal Urbano.<\/p>\n\n\n\n<p>Segundo informa\u00e7\u00f5es dos socorristas do Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (Samu), o motorista do \u00f4nibus seguia pela rua Os\u00f3rio Ribas de Paula. No momento que fez a curva para entrar no terminal, atingiu a v\u00edtima. Ela foi atingida pela lateral do ve\u00edculo e caiu no ch\u00e3o. Em seguida, as rodas traseiras do \u00f4nibus passaram por cima das pernas da mulher.<\/p>\n\n\n\n<p>Ainda de acordo com os socorristas, a idosa teve outras les\u00f5es al\u00e9m da mais grave, que atingiu o f\u00eamur. Ela recebeu atendimento ainda no local e foi encaminhada para o Hospital da Provid\u00eancia de Apucarana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>V\u00edtima de 73 anos foi atropelada enquanto estava atravessando a faixa de pedestre ao lado do terminal; idosa tamb\u00e9m teve fraturas expostas Uma idosa de 73 anos teve uma fratura no f\u00eamur, al\u00e9m de outras fraturas expostas, ap\u00f3s ser atropelada por um \u00f4nibus do transporte coletivo na manh\u00e3 desta quarta-feira (8) em\u00a0Apucarana, no norte do [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1257","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/1257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=1257"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/1257\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=1257"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=1257"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=1257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}