{"id":1205,"date":"2023-11-03T14:13:02","date_gmt":"2023-11-03T14:13:02","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=1205"},"modified":"2023-11-03T14:13:03","modified_gmt":"2023-11-03T14:13:03","slug":"apucarana-tera-corrida-maluca-nos-festejos-de-80-anos","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2023\/11\/03\/apucarana-tera-corrida-maluca-nos-festejos-de-80-anos\/","title":{"rendered":"Apucarana ter\u00e1 \u201ccorrida maluca\u201d nos festejos de 80 anos"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"676\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/11\/IMG_1655-1024x676-1.jpg\" alt=\"\" class=\"wp-image-1206\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/11\/IMG_1655-1024x676-1.jpg 1024w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/11\/IMG_1655-1024x676-1-600x396.jpg 600w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/11\/IMG_1655-1024x676-1-300x198.jpg 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/11\/IMG_1655-1024x676-1-768x507.jpg 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Inspirada em um dos desenhos animados mais emblem\u00e1ticos da inf\u00e2ncia de quem viveu a partir do final da d\u00e9cada de 60, onde dez pilotos disputavam corridas pelo pa\u00eds em seus carros doidos e cheios de estilo, Apucarana tamb\u00e9m ter\u00e1 a sua \u201ccorrida maluca\u201d. Idealizada e organizada pela Igreja Evang\u00e9lica Bola de Neve, o evento acontecer\u00e1 no dia 28 de janeiro dentro das festividades em comemora\u00e7\u00e3o aos 80 anos do munic\u00edpio, com apoio da prefeitura e Associa\u00e7\u00e3o Comercial, Industrial e de Servi\u00e7os de Apucarana (Acia).<\/p>\n\n\n\n<p>A promo\u00e7\u00e3o do evento, em trajeto ainda a ser determinando no entorno do Parque Municipal Jaboti, foi confirmado nesta quarta-feira (01\/01) durante reuni\u00e3o, no gabinete municipal, entre o prefeito J\u00fanior da Femac e o pastor Juliano Prado. No encontro, que contou com a participa\u00e7\u00e3o do secret\u00e1rio Municipal de Esportes, Tom Barros, e dos membros da igreja Jian Papa e Jossuela Pirelli, atual secret\u00e1ria Municipal da Assist\u00eancia Social, foram tratados ainda detalhes iniciais do planejamento. \u201cSem d\u00favidas, entre as dezenas de eventos que estamos programando para celebrar os 80 anos de Apucarana, este ser\u00e1 um dos mais surpreendentes, trazendo ainda mais divers\u00e3o e alegria\u201d, assinalou o prefeito J\u00fanior da Femac. Segundo ele, a prefeitura atuar\u00e1 como apoiadora, dando suporte em \u00e1reas como seguran\u00e7a, tr\u00e2nsito e log\u00edstica. \u201cVamos ainda disponibilizar ambul\u00e2ncia e profissionais de sa\u00fade para estarem de plant\u00e3o no local\u201d, assegurou o prefeito.<\/p>\n\n\n\n<p>O regulamento e canal de inscri\u00e7\u00e3o da \u201cCorrida Maluca Apucarana 80 anos\u201d est\u00e1 dispon\u00edvel no site&nbsp;<a href=\"https:\/\/www.sympla.com.br\/evento\/corrida-maluca-aniversario-de-80-anos-apucarana\">https:\/\/www.sympla.com.br\/evento\/corrida-maluca-aniversario-de-80-anos-apucarana<\/a>. Haver\u00e1 premia\u00e7\u00e3o por categorias, tendo como destaque o melhor carro com a tem\u00e1tica \u201cApucarana 80 anos\u201d.&nbsp; A participa\u00e7\u00e3o \u00e9 aberta a todos os interessados e a inscri\u00e7\u00e3o ser\u00e1 uma \u201ccesta b\u00e1sica\u201d. \u201cA Igreja Bola de Neve est\u00e1 presente em Apucarana h\u00e1 13 anos. Temos promovidos a evangeliza\u00e7\u00e3o atrav\u00e9s de eventos como skate e carros, e foi ent\u00e3o que surgiu este projeto, de presentear a cidade com a primeira \u201cCorrida Maluca\u201d. Agradecemos muito este apoio da prefeitura e certamente ser\u00e1 um grande evento, que pretendemos torn\u00e1-lo anual\u201d, disse pastor Juliano Prado.<\/p>\n\n\n\n<p>De acordo com ele, al\u00e9m de ser uma modalidade de \u201ccorrida\u201d conhecida e festejada mundialmente, tendo como refer\u00eancia o desenho aninado \u201cCorrida Maluca\u201d, com os hist\u00f3ricos personagens \u201cDick Vigarista\u201d, \u201cMuttley\u201d, \u201cPenepole Charmosa\u201d, entre outros, no Brasil o evento festivo vem sendo realizado em v\u00e1rios munic\u00edpios sempre com grande sucesso, sendo o mais famoso pela marca \u201cRed Bull, chamado \u201cLadeira Abaixo\u201d. \u201cAtrav\u00e9s da Bola de Neve, temos a igreja de Pinhais, na regi\u00e3o de Curitiba, que realiza a corrida maluca e esperamos t\u00ea-los presentes no evento em Apucarana\u201d, disse o pastor.<\/p>\n\n\n\n<p>Servi\u00e7o: Mais informa\u00e7\u00f5es sobre como participar da \u201cCorrida Maluca Apucarana 80 anos\u201d podem ser obtidas ainda pela rede social https:\/\/www.instagram.com\/boladeneveapucarana_pr, ou pelo WhatsApp (43) 99601-3240.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inspirada em um dos desenhos animados mais emblem\u00e1ticos da inf\u00e2ncia de quem viveu a partir do final da d\u00e9cada de 60, onde dez pilotos disputavam corridas pelo pa\u00eds em seus carros doidos e cheios de estilo, Apucarana tamb\u00e9m ter\u00e1 a sua \u201ccorrida maluca\u201d. Idealizada e organizada pela Igreja Evang\u00e9lica Bola de Neve, o evento acontecer\u00e1 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1205","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/1205","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=1205"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/1205\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=1205"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=1205"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=1205"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}