{"id":1198,"date":"2023-11-03T14:07:37","date_gmt":"2023-11-03T14:07:37","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=1198"},"modified":"2023-11-03T14:07:40","modified_gmt":"2023-11-03T14:07:40","slug":"jovem-maquiadora-de-marilandia-morre-apos-acidente-entre-caminhoes","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2023\/11\/03\/jovem-maquiadora-de-marilandia-morre-apos-acidente-entre-caminhoes\/","title":{"rendered":"Jovem maquiadora de Maril\u00e2ndia morre ap\u00f3s acidente entre caminh\u00f5es"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Aos 21 anos, Elen da Silva Braz foi v\u00edtima de um grave acidente e n\u00e3o resistiu aos ferimentos<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" decoding=\"async\" width=\"501\" height=\"501\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/11\/Elen-da-Silva-Braz-de-21-anos-00806851-0-202311031016-ScaleDownProportional-edited.webp\" alt=\"\" class=\"wp-image-1200\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/11\/Elen-da-Silva-Braz-de-21-anos-00806851-0-202311031016-ScaleDownProportional-edited.webp 501w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/11\/Elen-da-Silva-Braz-de-21-anos-00806851-0-202311031016-ScaleDownProportional-edited-300x300.webp 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/11\/Elen-da-Silva-Braz-de-21-anos-00806851-0-202311031016-ScaleDownProportional-edited-100x100.webp 100w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/11\/Elen-da-Silva-Braz-de-21-anos-00806851-0-202311031016-ScaleDownProportional-edited-150x150.webp 150w\" sizes=\"(max-width: 501px) 100vw, 501px\" \/><\/figure>\n\n\n\n<p>Uma jovem, de apenas 21 anos, moradora do distrito de Nova Moreira, em\u00a0<a href=\"https:\/\/tnonline.uol.com.br\/tags\/marilandia-do-sul\">Maril\u00e2ndia do Sul<\/a>, norte do Paran\u00e1, morreu nesta quinta-feira (2) ap\u00f3s grave acidente registrado entre dois caminh\u00f5es. A v\u00edtima, identificada como Elen da Silva Braz, estava viajando com o marido quando a colis\u00e3o aconteceu.<\/p>\n\n\n\n<p>Conforme apura\u00e7\u00f5es iniciais, o caminh\u00e3o em que o casal estava apresentou falhas mec\u00e2nicas na regi\u00e3o da cidade de Assis, em S\u00e3o Paulo. Elen teria descido do ve\u00edculo para buscar uma caixa de ferramentas e, nesse momento, uma outra carreta acabou colidindo contra o caminh\u00e3o dos jovens. As causas exatas do\u00a0<a href=\"https:\/\/tnonline.uol.com.br\/tags\/acidente?d=1\">acidente<\/a>\u00a0ainda est\u00e3o sendo apuradas pelas autoridades.<\/p>\n\n\n\n<p>A jovem sofreu ferimentos considerados graves, foi socorrida imediatamente e encaminhada para um hospital da regi\u00e3o. Elen Braz ficou em observa\u00e7\u00e3o na Unidade de Terapia Intensiva (UTI), mas n\u00e3o resistiu e faleceu na manh\u00e3 desta quinta. O marido dela tamb\u00e9m teria ficado ferido no acidente, mas o quadro de sa\u00fade dele n\u00e3o foi informado.<\/p>\n\n\n\n<p>Elen atuava como maquiadora e designer de sobrancelhas no distrito de Nova Moreira. Ao saberem sobre o grave acidente, moradores da localidade organizaram uma corrente de ora\u00e7\u00e3o pela recupera\u00e7\u00e3o dela. O falecimento precoce causou grande como\u00e7\u00e3o nas redes sociais.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Vel\u00f3rio e sepultamento<\/strong><\/h2>\n\n\n\n<p>Conforme informa\u00e7\u00f5es divulgadas na internet, o corpo da jovem est\u00e1 sendo velado na igreja de Nova Moreira. O sepultamento est\u00e1 previsto para acontecer na manh\u00e3 desta sexta-feira (3), no Cemit\u00e9rio Municipal de Maril\u00e2ndia do Sul.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aos 21 anos, Elen da Silva Braz foi v\u00edtima de um grave acidente e n\u00e3o resistiu aos ferimentos Uma jovem, de apenas 21 anos, moradora do distrito de Nova Moreira, em\u00a0Maril\u00e2ndia do Sul, norte do Paran\u00e1, morreu nesta quinta-feira (2) ap\u00f3s grave acidente registrado entre dois caminh\u00f5es. A v\u00edtima, identificada como Elen da Silva Braz, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1198","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/1198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=1198"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/1198\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=1198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=1198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=1198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}