{"id":1044,"date":"2023-10-23T12:09:59","date_gmt":"2023-10-23T12:09:59","guid":{"rendered":"https:\/\/www.fm945apucarana.com.br\/noticias\/?p=1044"},"modified":"2023-10-23T12:09:59","modified_gmt":"2023-10-23T12:09:59","slug":"jovem-de-21-anos-e-assassinado-com-tres-tiros-em-apucarana","status":"publish","type":"post","link":"https:\/\/www.fm945apucarana.com.br\/noticias\/2023\/10\/23\/jovem-de-21-anos-e-assassinado-com-tres-tiros-em-apucarana\/","title":{"rendered":"Jovem de 21 anos \u00e9 assassinado com tr\u00eas tiros em Apucarana"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Crime ocorreu ap\u00f3s uma discuss\u00e3o na Rua Zulmira, na Vila Reis, segundo a Pol\u00edcia Militar<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"834\" height=\"557\" src=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/10\/Samu-esteve-no-local-e-confirmou-o-obito-00803527-0-202310230721.webp\" alt=\"\" class=\"wp-image-1045\" style=\"aspect-ratio:1.497307001795332;width:750px;height:auto\" srcset=\"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/10\/Samu-esteve-no-local-e-confirmou-o-obito-00803527-0-202310230721.webp 834w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/10\/Samu-esteve-no-local-e-confirmou-o-obito-00803527-0-202310230721-600x401.webp 600w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/10\/Samu-esteve-no-local-e-confirmou-o-obito-00803527-0-202310230721-300x200.webp 300w, https:\/\/www.fm945apucarana.com.br\/noticias\/wp-content\/uploads\/2023\/10\/Samu-esteve-no-local-e-confirmou-o-obito-00803527-0-202310230721-768x513.webp 768w\" sizes=\"(max-width: 834px) 100vw, 834px\" \/><\/figure>\n\n\n\n<p>Um jovem de 21 anos foi morto a tiros na noite deste domingo (22) na Vila Reis, em Apucarana. O Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (Samu) chegou a ser acionado, mas o rapaz j\u00e1 estava morto quando os socorristas chegaram.<\/p>\n\n\n\n<p>Segundo as primeiras informa\u00e7\u00f5es obtidas pela reportagem no local junto \u00e0 Pol\u00edcia Militar (PM), o assassinato ocorreu ap\u00f3s uma briga na Rua Zulmira. A v\u00edtima foi morta com tr\u00eas tiros ap\u00f3s uma discuss\u00e3o entre dois homens. A v\u00edtima foi identificada como Carlos Manoel da Silva Macedo.<\/p>\n\n\n\n<p>O autor do homic\u00eddio fugiu do local e est\u00e1 sendo procurado pela PM.<\/p>\n\n\n\n<p>O Instituto M\u00e9dico Legal (IML) foi chamado para recolher o corpo, assim como a Pol\u00edcia Cient\u00edfica e investigadores da 17\u00aa Subdivis\u00e3o Policial (SDP) para dar in\u00edcio \u00e0s investiga\u00e7\u00f5es.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Crime ocorreu ap\u00f3s uma discuss\u00e3o na Rua Zulmira, na Vila Reis, segundo a Pol\u00edcia Militar Um jovem de 21 anos foi morto a tiros na noite deste domingo (22) na Vila Reis, em Apucarana. O Servi\u00e7o de Atendimento M\u00f3vel de Urg\u00eancia (Samu) chegou a ser acionado, mas o rapaz j\u00e1 estava morto quando os socorristas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1044","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"featured_image_urls":{"full":"","thumbnail":"","medium":"","medium_large":"","large":"","1536x1536":"","2048x2048":"","rivax-small":"","rivax-small-tall":"","rivax-small-square":"","rivax-small-masonry":"","rivax-medium":"","rivax-medium-square":"","rivax-medium-masonry":"","rivax-large":"","rivax-large-wide":"","woocommerce_thumbnail":"","woocommerce_single":"","woocommerce_gallery_thumbnail":""},"author_info":{"display_name":"Cayo Silva","author_link":"https:\/\/www.fm945apucarana.com.br\/noticias\/author\/cayosilva\/"},"category_info":"<a href=\"https:\/\/www.fm945apucarana.com.br\/noticias\/category\/uncategorized\/\" rel=\"category tag\">Uncategorized<\/a>","tag_info":"Uncategorized","comment_count":"0","_links":{"self":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/1044","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/comments?post=1044"}],"version-history":[{"count":0,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/posts\/1044\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/media?parent=1044"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/categories?post=1044"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.fm945apucarana.com.br\/noticias\/wp-json\/wp\/v2\/tags?post=1044"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}